{"id":87606,"date":"2021-11-03T10:55:06","date_gmt":"2021-11-03T13:55:06","guid":{"rendered":"https:\/\/www.institutodeengenharia.org.br\/site\/?p=87606"},"modified":"2021-11-03T10:55:06","modified_gmt":"2021-11-03T13:55:06","slug":"projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente","status":"publish","type":"post","link":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/11\/03\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\/","title":{"rendered":"Projeto agrega valor ao que \u00e9 produzido na Amaz\u00f4nia preservando o meio ambiente"},"content":{"rendered":"<div class=\"mc-column content-text active-extra-styles active-capital-letter\" data-block-type=\"unstyled\" data-block-weight=\"19\" data-block-id=\"1\">\n<p class=\"content-text__container theme-color-primary-first-letter\" data-track-category=\"Link no Texto\" data-track-links=\"\">Um grupo de cientistas brasileiros desenvolveu um\u00a0<span class=\"highlight highlighted\">projeto para valorizar produtos extra\u00eddos da floresta sem agress\u00f5es ao meio ambiente.<\/span><\/p>\n<\/div>\n<div class=\"wall protected-content\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"73\" data-block-id=\"2\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">O contato com a tecnologia \u00e9 o in\u00edcio da receita para uma revolu\u00e7\u00e3o. Representantes de comunidades amaz\u00f4nicas passaram a semana em treinamento em\u00a0<a href=\"https:\/\/g1.globo.com\/sp\/vale-do-paraiba-regiao\/cidade\/sao-jose-dos-campos\/\">S\u00e3o Jos\u00e9 dos Campos<\/a>, interior de S\u00e3o Paulo. S\u00e3o eles que v\u00e3o operar os equipamentos no meio da floresta. Ser\u00e3o apenas toques nas telas para acionar as m\u00e1quinas, todas computadorizadas e ligadas a sat\u00e9lites. Tudo para manter o padr\u00e3o e a qualidade do que ser\u00e1 produzido em diferentes biof\u00e1bricas.<\/p>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"48\" data-block-id=\"4\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\"><span class=\"highlight highlighted\">O projeto de cientistas, bancado por doa\u00e7\u00f5es, quer transformar frutos e castanhas em produtos de alto valor.<\/span> O cacau, por exemplo, vendido hoje de R$ 10 a R$ 14 o quilo, vai virar chocolate, que pode passar de R$ 200 o quilo, ainda mais se for para exporta\u00e7\u00e3o.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"56\" data-block-id=\"5\">\n<blockquote class=\"content-blockquote theme-border-color-primary-before\"><p>\u201cS\u00f3 o cacau, sem ser processado para o chocolate, comparado com a pecu\u00e1ria, \u00e9 sete vezes mais lucrativo por hectare por ano. O cacau como commoditie. Agora, quando voc\u00ea ainda agrega valor, 1.000%, 2.000%, \u00e9 realmente um novo paradigma, uma nova forma de enxergar o valor da floresta\u201d, explica Ismael Nobre, l\u00edder do Projeto Amaz\u00f4nia 4.0.<\/p><\/blockquote>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"62\" data-block-id=\"6\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Os equipamentos ainda est\u00e3o em testes e ser\u00e3o instalados em uma estrutura f\u00e1cil de montar &#8211; s\u00e3o apenas 26 parafusos -, de transportar &#8211; cabe tudo em uma caminhonete &#8211; e ficam com 100 m\u00b2. A energia ser\u00e1 solar e, quando for montada no meio da floresta, vai dar um ar futurista, mas tamb\u00e9m remeter aos povos mais antigos que vivem nela.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"41\" data-block-id=\"7\">\n<blockquote class=\"content-blockquote theme-border-color-primary-before\"><p>\u201cN\u00f3s precisamos unir a tecnologia com conhecimento tradicional, com a viv\u00eancia dos povos ind\u00edgenas. E eu acredito que, atrav\u00e9s dessa transforma\u00e7\u00e3o, n\u00f3s manteremos a floresta viva e em p\u00e9\u201d, afirma Telma Marques da Silva, da Uni\u00e3o das Mulheres Ind\u00edgenas da Amaz\u00f4nia.<\/p><\/blockquote>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"20\" data-block-id=\"9\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">A tecnologia, que pode ser estendida a outros produtos t\u00edpicos da\u00a0<a href=\"https:\/\/g1.globo.com\/meio-ambiente\/amazonia\/\">Amaz\u00f4nia<\/a>, \u00e9 o principal atrativo para os mais jovens.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"56\" data-block-id=\"10\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">\u201cO nosso trabalho com cacau, com chocolate, com cupua\u00e7u pode ser muito mais rent\u00e1vel que produ\u00e7\u00f5es extensivas de monocultura. E isso beneficia n\u00f3s, povos tradicionais, que estamos na floresta; beneficia quem est\u00e1 no sul do Brasil e beneficia quem est\u00e1 do outro lado do mundo\u201d, diz Luiz Henrique Lopes, da comunidade de Car\u00e3o, na Resex Tapaj\u00f3s-Arapiuns.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"63\" data-block-id=\"11\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">\u201c<span class=\"highlight highlighted\">N\u00f3s j\u00e1 temos estudos avan\u00e7ados com castanha, castanha-do-par\u00e1, que viram alimentos para o mercado vegano<\/span>, leite em p\u00f3, pasta para passar no p\u00e3o, cosm\u00e9ticos de alt\u00edssima qualidade. E assim vai. A\u00e7a\u00ed \u00e9 outro que est\u00e1 na lista, que j\u00e1 est\u00e1 come\u00e7ando tamb\u00e9m, e tamb\u00e9m\u00a0<span class=\"highlight highlighted\">estamos trabalhando quatro palmeiras da Amaz\u00f4nia para produ\u00e7\u00e3o de azeites gourmet, azeites finos para alta culin\u00e1ria<\/span>\u201d, explica Ismael Nobre.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"52\" data-block-id=\"12\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">H\u00e1 tr\u00eas gera\u00e7\u00f5es, a fam\u00edlia do seu Jo\u00e3o vive do cacau em um quilombo, em\u00a0<a href=\"https:\/\/g1.globo.com\/pa\/para\/cidade\/moju\/\">Moju<\/a>, no Par\u00e1. Criou tr\u00eas filhos vendendo o fruto barato. E, agora, o laborat\u00f3rio criativo da Amaz\u00f4nia deve ajudar a criar mais gente. \u201c\u00c9 uma inova\u00e7\u00e3o. Vai ser um esplendor para gente, com certeza\u201d, diz Jo\u00e3o.<\/p>\n<\/div>\n<div data-track-category=\"multicontent\" data-track-action=\"ultimo chunk conteudo\" data-track-noninteraction=\"false\" data-track-scroll=\"view\">\n<div class=\"block-podcast\"><a href=\"https:\/\/g1.globo.com\/jornal-nacional\/noticia\/2021\/10\/29\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente.ghtml\"><em><strong>Fonte: G1 Jornal Nacional<\/strong><\/em><\/a><\/div>\n<\/div>\n<\/div>\n<div class=\"content-ads content-ads--reveal\" data-block-type=\"ads\" data-block-id=\"8\">\n<div id=\"banner_materia2\" class=\"tag-manager-publicidade-container mc-has-reveal mc-has-ad-lazyload tag-manager-publicidade-banner_materia2 tag-manager-publicidade-container--carregado tag-manager-publicidade-container--visivel\" data-id=\"banner_materia2\" data-req=\"true\" data-google-query-id=\"CIPUnMKr_PMCFfeflQIdswcGJg\" data-cid=\"138369690428\" data-lid=\"5804874404\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Um grupo de cientistas brasileiros desenvolveu um\u00a0projeto para valorizar produtos extra\u00eddos da floresta sem agress\u00f5es ao meio ambiente. O contato com a tecnologia \u00e9 o in\u00edcio da receita para uma revolu\u00e7\u00e3o. Representantes de comunidades amaz\u00f4nicas passaram a semana em treinamento em\u00a0S\u00e3o Jos\u00e9 dos Campos, interior de S\u00e3o Paulo. S\u00e3o eles que v\u00e3o operar os equipamentos [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":87608,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1119,6],"tags":[],"class_list":{"0":"post-87606","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-amazonia-e-bioeconomia","8":"category-noticias"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Projeto agrega valor ao que \u00e9 produzido na Amaz\u00f4nia preservando o meio ambiente - Instituto de Engenharia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/11\/03\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projeto agrega valor ao que \u00e9 produzido na Amaz\u00f4nia preservando o meio ambiente\" \/>\n<meta property=\"og:description\" content=\"O projeto de cientistas brasileiros, bancado por doa\u00e7\u00f5es, quer transformar frutos e castanhas em produtos de alto valor por meio de biof\u00e1bricas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/11\/03\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto de Engenharia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/institutodeengenharia\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-03T13:55:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2021\/11\/environmental-protection-g6e5665317_1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bianca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Projeto agrega valor ao que \u00e9 produzido na Amaz\u00f4nia preservando o meio ambiente\" \/>\n<meta name=\"twitter:description\" content=\"O projeto de cientistas brasileiros, bancado por doa\u00e7\u00f5es, quer transformar frutos e castanhas em produtos de alto valor por meio de biof\u00e1bricas.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2021\/11\/environmental-protection-g6e5665317_1280.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@iengenharia\" \/>\n<meta name=\"twitter:site\" content=\"@iengenharia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bianca\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/11\\\/03\\\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/11\\\/03\\\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\\\/\"},\"author\":{\"name\":\"Bianca\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/person\\\/aeb64951c405e100d26d30b033dd423f\"},\"headline\":\"Projeto agrega valor ao que \u00e9 produzido na Amaz\u00f4nia preservando o meio ambiente\",\"datePublished\":\"2021-11-03T13:55:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/11\\\/03\\\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\\\/\"},\"wordCount\":553,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/11\\\/03\\\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/environmental-protection-g6e5665317_1280.webp\",\"articleSection\":[\"Amaz\u00f4nia e Bioeconomia\",\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/11\\\/03\\\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/11\\\/03\\\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\\\/\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/11\\\/03\\\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\\\/\",\"name\":\"Projeto agrega valor ao que \u00e9 produzido na Amaz\u00f4nia preservando o meio ambiente - Instituto de Engenharia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/11\\\/03\\\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/11\\\/03\\\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/environmental-protection-g6e5665317_1280.webp\",\"datePublished\":\"2021-11-03T13:55:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/11\\\/03\\\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/11\\\/03\\\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/11\\\/03\\\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/environmental-protection-g6e5665317_1280.webp\",\"contentUrl\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/environmental-protection-g6e5665317_1280.webp\",\"width\":790,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/11\\\/03\\\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projeto agrega valor ao que \u00e9 produzido na Amaz\u00f4nia preservando o meio ambiente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\",\"name\":\"Instituto de Engenharia\",\"description\":\"O Instituto de Engenharia promove a Engenharia em benef\u00edcio do desenvolvimento e da qualidade de vida da sociedade.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\",\"name\":\"Instituto de Engenharia\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo-novo-IE2018-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo-novo-IE2018-1.jpg\",\"width\":1486,\"height\":1879,\"caption\":\"Instituto de Engenharia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/institutodeengenharia\",\"https:\\\/\\\/x.com\\\/iengenharia\",\"https:\\\/\\\/www.instagram.com\\\/institutodeengenharia\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/instituto-de-engenharia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCXiCAlsSMe977vamW915HxA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/person\\\/aeb64951c405e100d26d30b033dd423f\",\"name\":\"Bianca\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6fbe9bff57405baf4c1e2c5c1811e072b558253974a9f9508f4678900c97c2a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6fbe9bff57405baf4c1e2c5c1811e072b558253974a9f9508f4678900c97c2a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6fbe9bff57405baf4c1e2c5c1811e072b558253974a9f9508f4678900c97c2a?s=96&d=mm&r=g\",\"caption\":\"Bianca\"},\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/author\\\/comunicacao1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Projeto agrega valor ao que \u00e9 produzido na Amaz\u00f4nia preservando o meio ambiente - Instituto de Engenharia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/11\/03\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\/","og_locale":"pt_BR","og_type":"article","og_title":"Projeto agrega valor ao que \u00e9 produzido na Amaz\u00f4nia preservando o meio ambiente","og_description":"O projeto de cientistas brasileiros, bancado por doa\u00e7\u00f5es, quer transformar frutos e castanhas em produtos de alto valor por meio de biof\u00e1bricas.","og_url":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/11\/03\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\/","og_site_name":"Instituto de Engenharia","article_publisher":"https:\/\/www.facebook.com\/institutodeengenharia","article_published_time":"2021-11-03T13:55:06+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2021\/11\/environmental-protection-g6e5665317_1280.jpg","type":"image\/jpeg"}],"author":"Bianca","twitter_card":"summary_large_image","twitter_title":"Projeto agrega valor ao que \u00e9 produzido na Amaz\u00f4nia preservando o meio ambiente","twitter_description":"O projeto de cientistas brasileiros, bancado por doa\u00e7\u00f5es, quer transformar frutos e castanhas em produtos de alto valor por meio de biof\u00e1bricas.","twitter_image":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2021\/11\/environmental-protection-g6e5665317_1280.jpg","twitter_creator":"@iengenharia","twitter_site":"@iengenharia","twitter_misc":{"Escrito por":"Bianca","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/11\/03\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\/#article","isPartOf":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/11\/03\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\/"},"author":{"name":"Bianca","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/person\/aeb64951c405e100d26d30b033dd423f"},"headline":"Projeto agrega valor ao que \u00e9 produzido na Amaz\u00f4nia preservando o meio ambiente","datePublished":"2021-11-03T13:55:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/11\/03\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\/"},"wordCount":553,"commentCount":0,"publisher":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization"},"image":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/11\/03\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2021\/11\/environmental-protection-g6e5665317_1280.webp","articleSection":["Amaz\u00f4nia e Bioeconomia","Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.institutodeengenharia.org.br\/site\/2021\/11\/03\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/11\/03\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\/","url":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/11\/03\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\/","name":"Projeto agrega valor ao que \u00e9 produzido na Amaz\u00f4nia preservando o meio ambiente - Instituto de Engenharia","isPartOf":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/11\/03\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\/#primaryimage"},"image":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/11\/03\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2021\/11\/environmental-protection-g6e5665317_1280.webp","datePublished":"2021-11-03T13:55:06+00:00","breadcrumb":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/11\/03\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.institutodeengenharia.org.br\/site\/2021\/11\/03\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/11\/03\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\/#primaryimage","url":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2021\/11\/environmental-protection-g6e5665317_1280.webp","contentUrl":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2021\/11\/environmental-protection-g6e5665317_1280.webp","width":790,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/11\/03\/projeto-agrega-valor-ao-que-e-produzido-na-amazonia-preservando-o-meio-ambiente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.institutodeengenharia.org.br\/site\/"},{"@type":"ListItem","position":2,"name":"Projeto agrega valor ao que \u00e9 produzido na Amaz\u00f4nia preservando o meio ambiente"}]},{"@type":"WebSite","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#website","url":"https:\/\/www.institutodeengenharia.org.br\/site\/","name":"Instituto de Engenharia","description":"O Instituto de Engenharia promove a Engenharia em benef\u00edcio do desenvolvimento e da qualidade de vida da sociedade.","publisher":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.institutodeengenharia.org.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization","name":"Instituto de Engenharia","url":"https:\/\/www.institutodeengenharia.org.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2019\/03\/logo-novo-IE2018-1.jpg","contentUrl":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2019\/03\/logo-novo-IE2018-1.jpg","width":1486,"height":1879,"caption":"Instituto de Engenharia"},"image":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/institutodeengenharia","https:\/\/x.com\/iengenharia","https:\/\/www.instagram.com\/institutodeengenharia\/","https:\/\/www.linkedin.com\/company\/instituto-de-engenharia\/","https:\/\/www.youtube.com\/channel\/UCXiCAlsSMe977vamW915HxA"]},{"@type":"Person","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/person\/aeb64951c405e100d26d30b033dd423f","name":"Bianca","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a6fbe9bff57405baf4c1e2c5c1811e072b558253974a9f9508f4678900c97c2a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a6fbe9bff57405baf4c1e2c5c1811e072b558253974a9f9508f4678900c97c2a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6fbe9bff57405baf4c1e2c5c1811e072b558253974a9f9508f4678900c97c2a?s=96&d=mm&r=g","caption":"Bianca"},"url":"https:\/\/www.institutodeengenharia.org.br\/site\/author\/comunicacao1\/"}]}},"_links":{"self":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts\/87606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/comments?post=87606"}],"version-history":[{"count":1,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts\/87606\/revisions"}],"predecessor-version":[{"id":87609,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts\/87606\/revisions\/87609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/media\/87608"}],"wp:attachment":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/media?parent=87606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/categories?post=87606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/tags?post=87606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}