{"id":87483,"date":"2021-10-27T16:08:19","date_gmt":"2021-10-27T19:08:19","guid":{"rendered":"https:\/\/www.institutodeengenharia.org.br\/site\/?p=87483"},"modified":"2021-10-27T16:08:19","modified_gmt":"2021-10-27T19:08:19","slug":"ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros","status":"publish","type":"post","link":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/10\/27\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\/","title":{"rendered":"IE NA M\u00cdDIA &#8211; Motivos e impactos de uma poss\u00edvel greve de caminhoneiros"},"content":{"rendered":"<p>Levando em conta o atual cen\u00e1rio e sabendo do impacto que as greves de caminhoneiros sempre causam na sociedade e no abastecimento de bens e servi\u00e7os, combust\u00edveis e diversas outras \u00e1reas.<\/p>\n<h2>Motivos e impactos de uma poss\u00edvel greve<\/h2>\n<p class=\"css-158dogj\">&#8220;Sem querer ser alarmista, n\u00f3s estamos frente a uma situa\u00e7\u00e3o muito ca\u00f3tica [&#8230;]&#8221;, comentou Ivan Whately,\u00a0vice-presidente de Atividades T\u00e9cnicas do Instituto de Engenharia de S\u00e3o Paulo.<\/p>\n<p class=\"css-158dogj\">Ele ainda observou que, al\u00e9m do problema do pre\u00e7o do combust\u00edvel, h\u00e1 a quest\u00e3o da qualidade das estradas, que muitas vezes s\u00e3o estradas que n\u00e3o est\u00e3o pavimentadas.<\/p>\n<p class=\"css-158dogj\">&#8220;Em termos de planejamento de infraestrutura do pa\u00eds, deveria haver maior cuidado por parte das nossas autoridades em diversificar os modais de transportes na matriz log\u00edstica principalmente, e isso n\u00e3o est\u00e1 ocorrendo. Existe uma preponder\u00e2ncia do uso do caminh\u00e3o em detrimento do uso da ferrovia, e mesmo da hidrovia. Hoje n\u00f3s temos em termos de malha ferrovi\u00e1ria em torno de 20 mil quil\u00f4metros de ferrovia [&#8230;] S\u00e3o 210 mil quil\u00f4metros de rodovias, o Brasil cuidou muito mais do modal rodovi\u00e1rio do que do ferrovi\u00e1rio&#8221;, destacou,\u00a0em entrevista \u00e0 ag\u00eancia de not\u00edcias Sputnik Brasil.<\/p>\n<p class=\"css-158dogj\">Por sua vez, Sergio Ejzenberg,\u00a0engenheiro e mestre em Transportes pela Escola Polit\u00e9cnica da Universidade de S\u00e3o Paulo, destacou que o &#8220;pre\u00e7o do \u00f3leo diesel, aparentemente, \u00e9 o estopim da greve, ou amea\u00e7a de greve, dos caminhoneiros, contudo, o caminhoneiro sabe que o pre\u00e7o do diesel n\u00e3o \u00e9 a causa do problema dele. Basta ter trabalho, ter demanda, que ele embute o pre\u00e7o mais caro no frete e continua trabalhando&#8221;.<\/p>\n<p class=\"css-158dogj\">&#8220;O problema \u00e9 que n\u00e3o h\u00e1 trabalho para todos, h\u00e1 mais caminh\u00f5es \u00e0 disposi\u00e7\u00e3o do que servi\u00e7o a ser feito. \u00c9 a crise econ\u00f4mica que destr\u00f3i a capacidade de sustento do caminhoneiro. Pode zerar o pre\u00e7o do diesel, sem frete continua a falta de sustento. Na Venezuela, praticamente zeraram o pre\u00e7o do combust\u00edvel, virou um pre\u00e7o irris\u00f3rio, e mesmo assim houve a destrui\u00e7\u00e3o total dos empregos e trabalho de todos, inclusive dos caminhoneiros. O problema \u00e9 crise econ\u00f4mica, n\u00e3o \u00e9 custo do combust\u00edvel, que \u00e9 resultado da crise, porque a instabilidade, que esse governo est\u00e1 causando com suas medidas estapaf\u00fardias, acaba promovendo a desvaloriza\u00e7\u00e3o do real em face ao d\u00f3lar e aumento, portanto, cada vez maior n\u00e3o s\u00f3 do combust\u00edvel, como de todos os insumos&#8221;, explicou Sergio Ejzenberg em entrevista \u00e0 mesma ag\u00eancia de not\u00edcias.<\/p>\n<p class=\"css-158dogj\">De acordo com Ivan Whately, uma poss\u00edvel greve de caminhoneiros impacta muito, primeiramente porque h\u00e1 uma grande ades\u00e3o.<\/p>\n<p class=\"css-158dogj\">O especialista ressalta que h\u00e1 aproximadamente 2,2 milh\u00f5es de caminh\u00f5es, sendo que cerca de 1,3 milh\u00e3o s\u00e3o de empresas e 700 mil s\u00e3o de aut\u00f4nomos, conseguindo uma grande ades\u00e3o em praticamente todos os eventos promovidos.<\/p>\n<p class=\"css-158dogj\">&#8220;As consequ\u00eancias na log\u00edstica s\u00e3o diretamente proporcionais \u00e0 ades\u00e3o que eles conseguem, e hoje no Brasil 82% das cargas que circulam nas estradas, vias urbanas, \u00e9 transportada por caminh\u00f5es [&#8230;] se excluirmos os gr\u00e3os e min\u00e9rios, assim mesmo eles transportam 60% das cargas&#8221;, observou Ivan Whately.<\/p>\n<p class=\"css-158dogj\">Al\u00e9m disso, ele ressaltou que uma paralisa\u00e7\u00e3o de caminh\u00f5es pode parar o pa\u00eds, e eles est\u00e3o desmotivados porque o diesel deve impactar muito no custo, devendo chegar a 30% do custo de log\u00edstica.<\/p>\n<p class=\"css-158dogj\">&#8220;Estamos muito na m\u00e3o dos caminhoneiros. O Brasil, durante o seu desenvolvimento, n\u00e3o teve uma preocupa\u00e7\u00e3o muito grande em diversificar os modais de transporte. Deveria ter investido em ferrovias, hidrovias, para n\u00e3o ficar tanto na depend\u00eancia de apenas um modo de transporte&#8221;, enfatizou.<\/p>\n<p class=\"css-158dogj\">Al\u00e9m disso, h\u00e1 uma situa\u00e7\u00e3o &#8220;muito s\u00e9ria&#8221; que \u00e9 a de planejamento de transporte no pa\u00eds, onde deve ser equacionada uma forma que preveja o uso mais equilibrado de todos os modos de transporte.<\/p>\n<h3>Medidas para amenizar impactos de uma poss\u00edvel greve<\/h3>\n<p class=\"css-158dogj\">No caso das ferrovias, h\u00e1 um crescimento muito grande de projetos que estavam &#8220;parados&#8221;, contudo, os investimentos ferrovi\u00e1rios s\u00e3o de longo prazo.<\/p>\n<p class=\"css-158dogj\">&#8220;Este ano foi aprovado um marco regulat\u00f3rio das ferrovias. Isso tamb\u00e9m vai trazer um grande impulso para poder melhorar a quantidade de quil\u00f4metros de ferrovias no Brasil, porque foi introduzida uma possibilidade de administra\u00e7\u00e3o de concess\u00e3o, que \u00e9 atrav\u00e9s de autoriza\u00e7\u00e3o. Isso diminui muito a burocracia das licita\u00e7\u00f5es e da transfer\u00eancia de uso de uma ferrovia pela iniciativa privada&#8221;, afirmou Ivan Whately.<\/p>\n<p class=\"css-158dogj\">Ele tamb\u00e9m recordou que estas ferrovias sempre s\u00e3o consideradas um modo de transporte que \u00e9 de grande capacidade, transportando mais toneladas do que um caminh\u00e3o, al\u00e9m de nunca trabalharem isoladamente, trabalhando sempre com interconex\u00e3o, integra\u00e7\u00e3o ou intermodais.<\/p>\n<p class=\"css-158dogj\">Contudo, o caminh\u00e3o n\u00e3o vai perder sua import\u00e2ncia, mesmo se crescer a ferrovia, &#8220;porque as ferrovias transportam em grandes quantidades, e para a distribui\u00e7\u00e3o nos grandes centros e grandes cidades, sempre necessitam de transferir a carga para um outro modo de menor capacidade, que \u00e9 o caminh\u00e3o, e este levar ao destino&#8221;, explicou Ivan Whately.<\/p>\n<p class=\"css-158dogj\">&#8220;Em termos de planejamento, devemos buscar esse equil\u00edbrio da matriz de transporte [&#8230;] Dotar o pa\u00eds de uma infraestrutura que seja vi\u00e1vel o ano todo, para todos os modos de transporte&#8221;, explicou.<\/p>\n<h4>Proposta do Bolsonaro aos caminhoneiros<\/h4>\n<p class=\"css-158dogj\">Dentre as reivindica\u00e7\u00f5es dos caminhoneiros est\u00e1 a redu\u00e7\u00e3o do pre\u00e7o do diesel e revis\u00e3o da pol\u00edtica de pre\u00e7os da Petrobras. Al\u00e9m disso, os caminhoneiros citam que a proposta de Bolsonaro de pagar o aux\u00edlio de R$ 400 \u00e9 &#8220;rid\u00edcula&#8221;.<\/p>\n<p class=\"css-158dogj\">Para Sergio Ejzenberg, o valor de R$ 400 &#8220;\u00e9 uma fala para agradar caminhoneiro, mas o pr\u00f3prio caminhoneiro sabe que isso n\u00e3o resolve absolutamente nada&#8221;.<\/p>\n<p class=\"css-158dogj\">&#8220;O que o caminhoneiro precisa \u00e9 de frete, \u00e9 de trabalho, \u00e9 de uma economia funcionando, uma economia confi\u00e1vel, \u00e9 tudo aquilo que este governo n\u00e3o est\u00e1 garantindo por suas a\u00e7\u00f5es descontroladas, exatamente na \u00e1rea da economia&#8221;, explicou.<\/p>\n<p class=\"css-158dogj\">Al\u00e9m disso, ele ressaltou que, &#8220;para que se evite uma greve, \u00e9 preciso seriedade na condu\u00e7\u00e3o do governo, e \u00e9 preciso dizer que, se aquele parar uma rodovia, vai ter aplicada contra ele as penas da lei, que s\u00e3o pesadas. Basta dois ou tr\u00eas motoristas para paralisar uma rodovia principal, e basta um policial e um guincho para tirar isso da rua&#8221;.<\/p>\n<p class=\"css-158dogj\">&#8220;\u00c9 preciso decis\u00e3o e \u00e9 preciso honestidade intelectual para acabar com esta situa\u00e7\u00e3o, que absolutamente n\u00e3o \u00e9 de interesse de ningu\u00e9m, muito menos dos caminhoneiros, porque a greve s\u00f3 vai servir, se for manipulada para que aconte\u00e7a, para ajudar a afundar a economia e, portanto, afundar ainda mais os caminhoneiros que j\u00e1 est\u00e3o sofrendo com a crise econ\u00f4mica&#8221;, explicou Sergio Ejzenberg. (com\u00a0Luiza Ramos e Felipe Camargo \/ ag\u00eancia\u00a0Sputnik Brasil)<\/p>\n<p><a href=\"https:\/\/www.jb.com.br\/economia\/2021\/10\/1033651-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros.html\"><em><strong>Fonte: Jornal do Brasil<\/strong><\/em><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Levando em conta o atual cen\u00e1rio e sabendo do impacto que as greves de caminhoneiros sempre causam na sociedade e no abastecimento de bens e servi\u00e7os, combust\u00edveis e diversas outras \u00e1reas. Motivos e impactos de uma poss\u00edvel greve &#8220;Sem querer ser alarmista, n\u00f3s estamos frente a uma situa\u00e7\u00e3o muito ca\u00f3tica [&#8230;]&#8221;, comentou Ivan Whately,\u00a0vice-presidente de [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":87485,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,6],"tags":[1171],"class_list":{"0":"post-87483","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ie-na-midia","8":"category-noticias","9":"tag-destaque-abaixo"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IE NA M\u00cdDIA - Motivos e impactos de uma poss\u00edvel greve de caminhoneiros - Instituto de Engenharia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/10\/27\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IE NA M\u00cdDIA - Motivos e impactos de uma poss\u00edvel greve de caminhoneiros\" \/>\n<meta property=\"og:description\" content=\"Entidades que representam os caminhoneiros se reuniram no s\u00e1bado (16) e deram prazo de 15 dias para que o governo de Jair Bolsonaro atenda as reivindica\u00e7\u00f5es da categoria. Caso contr\u00e1rio, os motoristas prometem parar a partir de 1\u00ba de novembro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/10\/27\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto de Engenharia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/institutodeengenharia\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-27T19:08:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2021\/10\/unnamed.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Bianca\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"IE NA M\u00cdDIA - Motivos e impactos de uma poss\u00edvel greve de caminhoneiros\" \/>\n<meta name=\"twitter:description\" content=\"Entidades que representam os caminhoneiros se reuniram no s\u00e1bado (16) e deram prazo de 15 dias para que o governo de Jair Bolsonaro atenda as reivindica\u00e7\u00f5es da categoria. Caso contr\u00e1rio, os motoristas prometem parar a partir de 1\u00ba de novembro\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2021\/10\/unnamed.png\" \/>\n<meta name=\"twitter:creator\" content=\"@iengenharia\" \/>\n<meta name=\"twitter:site\" content=\"@iengenharia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bianca\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/10\\\/27\\\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/10\\\/27\\\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\\\/\"},\"author\":{\"name\":\"Bianca\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/person\\\/aeb64951c405e100d26d30b033dd423f\"},\"headline\":\"IE NA M\u00cdDIA &#8211; Motivos e impactos de uma poss\u00edvel greve de caminhoneiros\",\"datePublished\":\"2021-10-27T19:08:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/10\\\/27\\\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\\\/\"},\"wordCount\":1174,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/10\\\/27\\\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/unnamed.webp\",\"keywords\":[\"destaque-abaixo\"],\"articleSection\":[\"IE NA M\u00cdDIA\",\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/10\\\/27\\\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/10\\\/27\\\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\\\/\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/10\\\/27\\\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\\\/\",\"name\":\"IE NA M\u00cdDIA - Motivos e impactos de uma poss\u00edvel greve de caminhoneiros - Instituto de Engenharia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/10\\\/27\\\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/10\\\/27\\\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/unnamed.webp\",\"datePublished\":\"2021-10-27T19:08:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/10\\\/27\\\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/10\\\/27\\\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/10\\\/27\\\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/unnamed.webp\",\"contentUrl\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/unnamed.webp\",\"width\":512,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2021\\\/10\\\/27\\\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IE NA M\u00cdDIA &#8211; Motivos e impactos de uma poss\u00edvel greve de caminhoneiros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\",\"name\":\"Instituto de Engenharia\",\"description\":\"O Instituto de Engenharia promove a Engenharia em benef\u00edcio do desenvolvimento e da qualidade de vida da sociedade.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\",\"name\":\"Instituto de Engenharia\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo-novo-IE2018-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo-novo-IE2018-1.jpg\",\"width\":1486,\"height\":1879,\"caption\":\"Instituto de Engenharia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/institutodeengenharia\",\"https:\\\/\\\/x.com\\\/iengenharia\",\"https:\\\/\\\/www.instagram.com\\\/institutodeengenharia\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/instituto-de-engenharia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCXiCAlsSMe977vamW915HxA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/person\\\/aeb64951c405e100d26d30b033dd423f\",\"name\":\"Bianca\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6fbe9bff57405baf4c1e2c5c1811e072b558253974a9f9508f4678900c97c2a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6fbe9bff57405baf4c1e2c5c1811e072b558253974a9f9508f4678900c97c2a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a6fbe9bff57405baf4c1e2c5c1811e072b558253974a9f9508f4678900c97c2a?s=96&d=mm&r=g\",\"caption\":\"Bianca\"},\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/author\\\/comunicacao1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IE NA M\u00cdDIA - Motivos e impactos de uma poss\u00edvel greve de caminhoneiros - Instituto de Engenharia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/10\/27\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\/","og_locale":"pt_BR","og_type":"article","og_title":"IE NA M\u00cdDIA - Motivos e impactos de uma poss\u00edvel greve de caminhoneiros","og_description":"Entidades que representam os caminhoneiros se reuniram no s\u00e1bado (16) e deram prazo de 15 dias para que o governo de Jair Bolsonaro atenda as reivindica\u00e7\u00f5es da categoria. Caso contr\u00e1rio, os motoristas prometem parar a partir de 1\u00ba de novembro","og_url":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/10\/27\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\/","og_site_name":"Instituto de Engenharia","article_publisher":"https:\/\/www.facebook.com\/institutodeengenharia","article_published_time":"2021-10-27T19:08:19+00:00","og_image":[{"width":512,"height":250,"url":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2021\/10\/unnamed.png","type":"image\/png"}],"author":"Bianca","twitter_card":"summary_large_image","twitter_title":"IE NA M\u00cdDIA - Motivos e impactos de uma poss\u00edvel greve de caminhoneiros","twitter_description":"Entidades que representam os caminhoneiros se reuniram no s\u00e1bado (16) e deram prazo de 15 dias para que o governo de Jair Bolsonaro atenda as reivindica\u00e7\u00f5es da categoria. Caso contr\u00e1rio, os motoristas prometem parar a partir de 1\u00ba de novembro","twitter_image":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2021\/10\/unnamed.png","twitter_creator":"@iengenharia","twitter_site":"@iengenharia","twitter_misc":{"Escrito por":"Bianca","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/10\/27\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\/#article","isPartOf":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/10\/27\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\/"},"author":{"name":"Bianca","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/person\/aeb64951c405e100d26d30b033dd423f"},"headline":"IE NA M\u00cdDIA &#8211; Motivos e impactos de uma poss\u00edvel greve de caminhoneiros","datePublished":"2021-10-27T19:08:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/10\/27\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\/"},"wordCount":1174,"commentCount":0,"publisher":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization"},"image":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/10\/27\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\/#primaryimage"},"thumbnailUrl":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2021\/10\/unnamed.webp","keywords":["destaque-abaixo"],"articleSection":["IE NA M\u00cdDIA","Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.institutodeengenharia.org.br\/site\/2021\/10\/27\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/10\/27\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\/","url":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/10\/27\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\/","name":"IE NA M\u00cdDIA - Motivos e impactos de uma poss\u00edvel greve de caminhoneiros - Instituto de Engenharia","isPartOf":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/10\/27\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\/#primaryimage"},"image":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/10\/27\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\/#primaryimage"},"thumbnailUrl":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2021\/10\/unnamed.webp","datePublished":"2021-10-27T19:08:19+00:00","breadcrumb":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/10\/27\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.institutodeengenharia.org.br\/site\/2021\/10\/27\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/10\/27\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\/#primaryimage","url":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2021\/10\/unnamed.webp","contentUrl":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2021\/10\/unnamed.webp","width":512,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2021\/10\/27\/ie-na-midia-motivos-e-impactos-de-uma-possivel-greve-de-caminhoneiros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.institutodeengenharia.org.br\/site\/"},{"@type":"ListItem","position":2,"name":"IE NA M\u00cdDIA &#8211; Motivos e impactos de uma poss\u00edvel greve de caminhoneiros"}]},{"@type":"WebSite","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#website","url":"https:\/\/www.institutodeengenharia.org.br\/site\/","name":"Instituto de Engenharia","description":"O Instituto de Engenharia promove a Engenharia em benef\u00edcio do desenvolvimento e da qualidade de vida da sociedade.","publisher":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.institutodeengenharia.org.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization","name":"Instituto de Engenharia","url":"https:\/\/www.institutodeengenharia.org.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2019\/03\/logo-novo-IE2018-1.jpg","contentUrl":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2019\/03\/logo-novo-IE2018-1.jpg","width":1486,"height":1879,"caption":"Instituto de Engenharia"},"image":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/institutodeengenharia","https:\/\/x.com\/iengenharia","https:\/\/www.instagram.com\/institutodeengenharia\/","https:\/\/www.linkedin.com\/company\/instituto-de-engenharia\/","https:\/\/www.youtube.com\/channel\/UCXiCAlsSMe977vamW915HxA"]},{"@type":"Person","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/person\/aeb64951c405e100d26d30b033dd423f","name":"Bianca","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a6fbe9bff57405baf4c1e2c5c1811e072b558253974a9f9508f4678900c97c2a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a6fbe9bff57405baf4c1e2c5c1811e072b558253974a9f9508f4678900c97c2a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a6fbe9bff57405baf4c1e2c5c1811e072b558253974a9f9508f4678900c97c2a?s=96&d=mm&r=g","caption":"Bianca"},"url":"https:\/\/www.institutodeengenharia.org.br\/site\/author\/comunicacao1\/"}]}},"_links":{"self":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts\/87483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/comments?post=87483"}],"version-history":[{"count":1,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts\/87483\/revisions"}],"predecessor-version":[{"id":87486,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts\/87483\/revisions\/87486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/media\/87485"}],"wp:attachment":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/media?parent=87483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/categories?post=87483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/tags?post=87483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}