{"id":16528,"date":"2009-09-01T22:20:40","date_gmt":"2009-09-01T22:20:40","guid":{"rendered":"https:\/\/www.institutodeengenharia.org.br\/?p=16528"},"modified":"2009-09-01T13:52:46","modified_gmt":"2009-09-01T13:52:46","slug":"consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro","status":"publish","type":"post","link":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/09\/01\/consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro\/","title":{"rendered":"Consulta p\u00fablica do trem de alta velocidade termina em 15 de setembro"},"content":{"rendered":"<p><em>Linha pretende ligar Campinas, S\u00e3o Paulo e Rio de Janeiro. <br \/>\nSaiba tudo sobre o projeto do primeiro trem-bala brasileiro. <br \/>\n<\/em><br \/>\nCaso os planos do governo federal se confirmem, em cinco anos ser\u00e1 poss\u00edvel ir de S\u00e3o Paulo ao Rio de Janeiro sobre trilhos, em um trem a 280 km\/h. A meta \u00e9 que o Trem de Alta Velocidade (TAV) esteja pronto para a Copa do Mundo de 2014 e ligue Campinas, S\u00e3o Paulo e Rio de Janeiro, em mais de 510 km de trilhos. Por\u00e9m, o custo para que o trem-bala brasileiro saia do papel \u00e9 alto: R$ 34,6 bilh\u00f5es. <\/p>\n<p>O TAV est\u00e1 em fase de consulta p\u00fablica, at\u00e9 15 de setembro. De acordo com a Ag\u00eancia Nacional de Transportes Terrestres (ANTT), at\u00e9 a ter\u00e7a-feira (25) tinham sido recebidas cerca de 400 contribui\u00e7\u00f5es. O edital deve estar conclu\u00eddo at\u00e9 o fim do setembro e a licita\u00e7\u00e3o est\u00e1 prevista para acontecer at\u00e9 o fim do ano. O in\u00edcio das obras, no entanto, depende de eventuais altera\u00e7\u00f5es feitas no projeto pelo vencedor da licita\u00e7\u00e3o. <br \/>\nO projeto prev\u00ea a constru\u00e7\u00e3o de 90,9 km de t\u00faneis, 107,8 km de viadutos e 312,1 km de trilhos na superf\u00edcie. O trem passar\u00e1 por um t\u00fanel sob a capital paulista, por exemplo, porque os t\u00e9cnicos avaliaram que o impacto seria menor por causa das desapropria\u00e7\u00f5es necess\u00e1rias e os custos delas em uma \u00e1rea de grande densidade populacional. <\/p>\n<p>J\u00e1 ficou definido que o governo federal arcar\u00e1 com os custos de desapropria\u00e7\u00f5es nos munic\u00edpios por onde o trem passar\u00e1. \u201cN\u00f3s j\u00e1 nos comprometemos a pagar a desapropria\u00e7\u00e3o, isso j\u00e1 est\u00e1 acertado com o secret\u00e1rio do Tesouro\u201d, afirma o secret\u00e1rio de Pol\u00edtica Nacional de Transportes, do Minist\u00e9rio dos Transportes, Marcelo Perrupato. A modelagem financeira do projeto, no entanto, ainda n\u00e3o est\u00e1 totalmente fechada. <\/p>\n<p>Um dos objetivos do governo \u00e9 ter uma liga\u00e7\u00e3o r\u00e1pida entre importantes aeroportos do pa\u00eds. O projeto prev\u00ea que o trem passar\u00e1 pelo Aeroporto de Viracopos, em Campinas, de Guarulhos, na Grande S\u00e3o Paulo, e Tom Jobim (Gale\u00e3o), no Rio de Janeiro. Al\u00e9m disso, haver\u00e1 uma esta\u00e7\u00e3o no Aeroporto Campo de Marte, na Zona Norte de S\u00e3o Paulo. O ponto de parada na capital paulista foi definido no local porque a \u00e1rea do aeroporto \u00e9 federal. <\/p>\n<p>O tra\u00e7ado referencial prev\u00ea esta\u00e7\u00f5es consideradas fundamentais para o governo e sugere outras. Mas o cons\u00f3rcio que vencer a licita\u00e7\u00e3o poder\u00e1 fazer mudan\u00e7as no tra\u00e7ado. As esta\u00e7\u00f5es previstas ficam em Campinas, Viracopos, S\u00e3o Paulo, Guarulhos, S\u00e3o Jos\u00e9 dos Campos, Volta Redonda\/Barra Mansa, Rio de Janeiro e Gale\u00e3o. As sugeridas est\u00e3o em Jundia\u00ed e Aparecida, em S\u00e3o Paulo, e Resende, no Rio. <\/p>\n<p>Caso os planos do governo federal se confirmem, em cinco anos ser\u00e1 poss\u00edvel ir de S\u00e3o Paulo ao Rio de Janeiro sobre trilhos, em um trem a 280 km\/h. A meta \u00e9 que o Trem de Alta Velocidade (TAV) esteja pronto para a Copa do Mundo de 2014 e ligue Campinas, S\u00e3o Paulo e Rio de Janeiro, em mais de 510 km de trilhos. Por\u00e9m, o custo para que o trem-bala brasileiro saia do papel \u00e9 alto: R$ 34,6 bilh\u00f5es. <\/p>\n<p>O TAV est\u00e1 em fase de consulta p\u00fablica, at\u00e9 15 de setembro. De acordo com a Ag\u00eancia Nacional de Transportes Terrestres (ANTT), at\u00e9 a ter\u00e7a-feira (25) tinham sido recebidas cerca de 400 contribui\u00e7\u00f5es. O edital deve estar conclu\u00eddo at\u00e9 o fim do setembro e a licita\u00e7\u00e3o est\u00e1 prevista para acontecer at\u00e9 o fim do ano. O in\u00edcio das obras, no entanto, depende de eventuais altera\u00e7\u00f5es feitas no projeto pelo vencedor da licita\u00e7\u00e3o. <\/p>\n<p>O projeto prev\u00ea a constru\u00e7\u00e3o de 90,9 km de t\u00faneis, 107,8 km de viadutos e 312,1 km de trilhos na superf\u00edcie. O trem passar\u00e1 por um t\u00fanel sob a capital paulista, por exemplo, porque os t\u00e9cnicos avaliaram que o impacto seria menor por causa das desapropria\u00e7\u00f5es necess\u00e1rias e os custos delas em uma \u00e1rea de grande densidade populacional. <\/p>\n<p>J\u00e1 ficou definido que o governo federal arcar\u00e1 com os custos de desapropria\u00e7\u00f5es nos munic\u00edpios por onde o trem passar\u00e1. \u201cN\u00f3s j\u00e1 nos comprometemos a pagar a desapropria\u00e7\u00e3o, isso j\u00e1 est\u00e1 acertado com o secret\u00e1rio do Tesouro\u201d, afirma o secret\u00e1rio de Pol\u00edtica Nacional de Transportes, do Minist\u00e9rio dos Transportes, Marcelo Perrupato. A modelagem financeira do projeto, no entanto, ainda n\u00e3o est\u00e1 totalmente fechada. <\/p>\n<p>Um dos objetivos do governo \u00e9 ter uma liga\u00e7\u00e3o r\u00e1pida entre importantes aeroportos do pa\u00eds. O projeto prev\u00ea que o trem passar\u00e1 pelo Aeroporto de Viracopos, em Campinas, de Guarulhos, na Grande S\u00e3o Paulo, e Tom Jobim (Gale\u00e3o), no Rio de Janeiro. Al\u00e9m disso, haver\u00e1 uma esta\u00e7\u00e3o no Aeroporto Campo de Marte, na Zona Norte de S\u00e3o Paulo. O ponto de parada na capital paulista foi definido no local porque a \u00e1rea do aeroporto \u00e9 federal. <\/p>\n<p>O tra\u00e7ado referencial prev\u00ea esta\u00e7\u00f5es consideradas fundamentais para o governo e sugere outras. Mas o cons\u00f3rcio que vencer a licita\u00e7\u00e3o poder\u00e1 fazer mudan\u00e7as no tra\u00e7ado. As esta\u00e7\u00f5es previstas ficam em Campinas, Viracopos, S\u00e3o Paulo, Guarulhos, S\u00e3o Jos\u00e9 dos Campos, Volta Redonda\/Barra Mansa, Rio de Janeiro e Gale\u00e3o. As sugeridas est\u00e3o em Jundia\u00ed e Aparecida, em S\u00e3o Paulo, e Resende, no Rio. <\/p>\n<p>A velocidade m\u00e1xima prevista no projeto \u00e9 de 350 km\/h, mas o objetivo \u00e9 que o trem percorra o trecho entre Rio e S\u00e3o Paulo a 280 km\/h. Para comparar com os trens conhecidos pelos paulistanos, os do Metr\u00f4 da capital paulista circulam, no m\u00e1ximo, a 80 km\/h e os da Companhia Paulista de Trens Metropolitanos (CPTM), a 90 km\/h. Nos dois casos, a velocidade n\u00e3o pode ser maior porque a dist\u00e2ncia entre as esta\u00e7\u00f5es \u00e9 pequena \u2013 no Metr\u00f4, uma parada fica, em m\u00e9dia, a 1 km da outra. <\/p>\n<p><strong>Viabilidade e concess\u00e3o<\/strong> <\/p>\n<p>O engenheiro Roberto Dias David, gerente de projeto do TAV Brasil da ANTT, diz que os estudos mostram a viabilidade do trem, apesar dos custos. \u201cA gente pretende, com a implanta\u00e7\u00e3o desse projeto, introduzir um novo meio de transporte de passageiros no pa\u00eds\u201d, afirmou durante apresenta\u00e7\u00e3o na 15\u00aa Semana de Tecnologia Metroferrovi\u00e1ria, realizada na capital paulista. A expectativa \u00e9 de que 50% dos cerca de 33 milh\u00f5es de passageiros que viajam entre Campinas, S\u00e3o Paulo e Rio de Janeiro todos os anos possam ser absorvidos pelo trem. <br \/>\nOs cons\u00f3rcios interessados em participar da licita\u00e7\u00e3o precisam ter experi\u00eancia em constru\u00e7\u00e3o e opera\u00e7\u00e3o de trens de alta velocidade. De acordo com Marcelo Perrupato, h\u00e1 dois crit\u00e9rios importantes para vencer a concorr\u00eancia: a proposta que exigir menos aporte de recursos p\u00fablicos e aquela que oferecer a melhor oferta de transfer\u00eancia de tecnologia. <\/p>\n<p>\u201cSe esse projeto nosso tiver sucesso, e n\u00f3s acreditamos que ter\u00e1, pode significar tamb\u00e9m trazer ao pa\u00eds conhecimento que poder\u00e1 ser aplicado em futuras expans\u00f5es\u201d, afirmou. A Empresa de Transporte Ferrovi\u00e1rio de Alta Velocidade (ETAV) seria a respons\u00e1vel pela tarefa. \u201cSer\u00e1 um n\u00facleo de profissionais que v\u00e3o participar de todas as etapas do trem.\u201d <\/p>\n<p>Apesar de o tempo de concess\u00e3o ainda estar em estudo, existe a possibilidade de ela ser de 40 anos. \u201cEstamos estudando porque o prazo n\u00e3o pode ser muito curto, porque o investimento \u00e9 muito alto\u201d, disse o secret\u00e1rio. Ele garante, tamb\u00e9m, que j\u00e1 h\u00e1 interessados em construir e operar o trem no Brasil. Segundo Perrupato, haver\u00e1 um \u201cbom financiamento\u201d dispon\u00edvel para o projeto. \u201cN\u00f3s n\u00e3o pretendemos que exista algu\u00e9m com R$ 20 bilh\u00f5es no bolso para colocar em um projeto desses e gastar em 4 anos de obra.\u201d <\/p>\n<p>As tarifas do trem, segundo o secret\u00e1rio, ser\u00e3o livres. O projeto prev\u00ea, por exemplo, tarifas de R$ 200 na classe econ\u00f4mica e R$ 325 na executiva na viagem entre Rio de Janeiro e S\u00e3o Paulo, dentro do hor\u00e1rio considerado de pico. \u201cA tarifa \u00e9 livre. O governo estabeleceu um teto tarif\u00e1rio que \u00e9 competitivo com \u00f4nibus e avi\u00e3o, e fizemos uma modelagem para saber se esse projeto se pagava, ou n\u00e3o. E, com essa tarifa, ele se paga\u201d, afirmou Perrupato. <\/p>\n<p>Questionado se existe a possibilidade de o TAV n\u00e3o sair do papel, o secret\u00e1rio se mostrou confiante em rela\u00e7\u00e3o ao projeto. \u201cEu n\u00e3o acredito nisso, eu nunca vi tanta integra\u00e7\u00e3o. E isso n\u00e3o est\u00e1 s\u00f3 no governo federal. Isso est\u00e1 no estado do Rio, em S\u00e3o Paulo e nas cidades envolvidas. Todo mundo entendeu que esse projeto tem um grande impacto futuro.\u201d <\/p>\n<p><a target=\"_blank\" href=\"http:\/\/www.tavbrasil.gov.br\/Tracado.asp\">CLIQUE AQUI<\/a> E CONFIRA O TRA\u00c7ADO E OUTRAS INFORMA\u00c7\u00d5ES SOBRE O TAV<\/p>\n<p><b>Autor: G1<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Linha pretende ligar Campinas, S\u00e3o Paulo e Rio de Janeiro. Saiba tudo sobre o projeto do primeiro trem-bala brasileiro. Caso os planos do governo federal se confirmem, em cinco anos ser\u00e1 poss\u00edvel ir de S\u00e3o Paulo ao Rio de Janeiro sobre trilhos, em um trem a 280 km\/h. A meta \u00e9 que o Trem de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,41],"tags":[],"class_list":{"0":"post-16528","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-noticias","7":"category-transportes"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Consulta p\u00fablica do trem de alta velocidade termina em 15 de setembro - Instituto de Engenharia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/09\/01\/consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consulta p\u00fablica do trem de alta velocidade termina em 15 de setembro - Instituto de Engenharia\" \/>\n<meta property=\"og:description\" content=\"Linha pretende ligar Campinas, S\u00e3o Paulo e Rio de Janeiro. Saiba tudo sobre o projeto do primeiro trem-bala brasileiro. Caso os planos do governo federal se confirmem, em cinco anos ser\u00e1 poss\u00edvel ir de S\u00e3o Paulo ao Rio de Janeiro sobre trilhos, em um trem a 280 km\/h. A meta \u00e9 que o Trem de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/09\/01\/consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto de Engenharia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/institutodeengenharia\" \/>\n<meta property=\"article:published_time\" content=\"2009-09-01T22:20:40+00:00\" \/>\n<meta name=\"author\" content=\"TMax Tecnologia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@iengenharia\" \/>\n<meta name=\"twitter:site\" content=\"@iengenharia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"TMax Tecnologia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/09\\\/01\\\/consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/09\\\/01\\\/consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro\\\/\"},\"author\":{\"name\":\"TMax Tecnologia\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/person\\\/3b1ff109facef084739fc2edcb9a127f\"},\"headline\":\"Consulta p\u00fablica do trem de alta velocidade termina em 15 de setembro\",\"datePublished\":\"2009-09-01T22:20:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/09\\\/01\\\/consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro\\\/\"},\"wordCount\":1498,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\"},\"articleSection\":[\"Not\u00edcias\",\"Transportes\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/09\\\/01\\\/consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/09\\\/01\\\/consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro\\\/\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/09\\\/01\\\/consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro\\\/\",\"name\":\"Consulta p\u00fablica do trem de alta velocidade termina em 15 de setembro - Instituto de Engenharia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#website\"},\"datePublished\":\"2009-09-01T22:20:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/09\\\/01\\\/consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/09\\\/01\\\/consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/09\\\/01\\\/consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consulta p\u00fablica do trem de alta velocidade termina em 15 de setembro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\",\"name\":\"Instituto de Engenharia\",\"description\":\"O Instituto de Engenharia promove a Engenharia em benef\u00edcio do desenvolvimento e da qualidade de vida da sociedade.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\",\"name\":\"Instituto de Engenharia\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo-novo-IE2018-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo-novo-IE2018-1.jpg\",\"width\":1486,\"height\":1879,\"caption\":\"Instituto de Engenharia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/institutodeengenharia\",\"https:\\\/\\\/x.com\\\/iengenharia\",\"https:\\\/\\\/www.instagram.com\\\/institutodeengenharia\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/instituto-de-engenharia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCXiCAlsSMe977vamW915HxA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/person\\\/3b1ff109facef084739fc2edcb9a127f\",\"name\":\"TMax Tecnologia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g\",\"caption\":\"TMax Tecnologia\"},\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/author\\\/tmax\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consulta p\u00fablica do trem de alta velocidade termina em 15 de setembro - Instituto de Engenharia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/09\/01\/consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro\/","og_locale":"pt_BR","og_type":"article","og_title":"Consulta p\u00fablica do trem de alta velocidade termina em 15 de setembro - Instituto de Engenharia","og_description":"Linha pretende ligar Campinas, S\u00e3o Paulo e Rio de Janeiro. Saiba tudo sobre o projeto do primeiro trem-bala brasileiro. Caso os planos do governo federal se confirmem, em cinco anos ser\u00e1 poss\u00edvel ir de S\u00e3o Paulo ao Rio de Janeiro sobre trilhos, em um trem a 280 km\/h. A meta \u00e9 que o Trem de [&hellip;]","og_url":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/09\/01\/consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro\/","og_site_name":"Instituto de Engenharia","article_publisher":"https:\/\/www.facebook.com\/institutodeengenharia","article_published_time":"2009-09-01T22:20:40+00:00","author":"TMax Tecnologia","twitter_card":"summary_large_image","twitter_creator":"@iengenharia","twitter_site":"@iengenharia","twitter_misc":{"Escrito por":"TMax Tecnologia","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/09\/01\/consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro\/#article","isPartOf":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/09\/01\/consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro\/"},"author":{"name":"TMax Tecnologia","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/person\/3b1ff109facef084739fc2edcb9a127f"},"headline":"Consulta p\u00fablica do trem de alta velocidade termina em 15 de setembro","datePublished":"2009-09-01T22:20:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/09\/01\/consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro\/"},"wordCount":1498,"commentCount":0,"publisher":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization"},"articleSection":["Not\u00edcias","Transportes"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.institutodeengenharia.org.br\/site\/2009\/09\/01\/consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/09\/01\/consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro\/","url":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/09\/01\/consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro\/","name":"Consulta p\u00fablica do trem de alta velocidade termina em 15 de setembro - Instituto de Engenharia","isPartOf":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#website"},"datePublished":"2009-09-01T22:20:40+00:00","breadcrumb":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/09\/01\/consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.institutodeengenharia.org.br\/site\/2009\/09\/01\/consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/09\/01\/consulta-publica-do-trem-de-alta-velocidade-termina-em-15-de-setembro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.institutodeengenharia.org.br\/site\/"},{"@type":"ListItem","position":2,"name":"Consulta p\u00fablica do trem de alta velocidade termina em 15 de setembro"}]},{"@type":"WebSite","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#website","url":"https:\/\/www.institutodeengenharia.org.br\/site\/","name":"Instituto de Engenharia","description":"O Instituto de Engenharia promove a Engenharia em benef\u00edcio do desenvolvimento e da qualidade de vida da sociedade.","publisher":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.institutodeengenharia.org.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization","name":"Instituto de Engenharia","url":"https:\/\/www.institutodeengenharia.org.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2019\/03\/logo-novo-IE2018-1.jpg","contentUrl":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2019\/03\/logo-novo-IE2018-1.jpg","width":1486,"height":1879,"caption":"Instituto de Engenharia"},"image":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/institutodeengenharia","https:\/\/x.com\/iengenharia","https:\/\/www.instagram.com\/institutodeengenharia\/","https:\/\/www.linkedin.com\/company\/instituto-de-engenharia\/","https:\/\/www.youtube.com\/channel\/UCXiCAlsSMe977vamW915HxA"]},{"@type":"Person","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/person\/3b1ff109facef084739fc2edcb9a127f","name":"TMax Tecnologia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g","caption":"TMax Tecnologia"},"url":"https:\/\/www.institutodeengenharia.org.br\/site\/author\/tmax\/"}]}},"_links":{"self":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts\/16528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/comments?post=16528"}],"version-history":[{"count":0,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts\/16528\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/media?parent=16528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/categories?post=16528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/tags?post=16528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}