{"id":16521,"date":"2009-08-27T22:20:32","date_gmt":"2009-08-27T22:20:32","guid":{"rendered":"https:\/\/www.institutodeengenharia.org.br\/?p=16521"},"modified":"2009-08-27T17:18:58","modified_gmt":"2009-08-27T17:18:58","slug":"sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja","status":"publish","type":"post","link":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/27\/sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja\/","title":{"rendered":"SEP ou SP: quem dar\u00e1 a palavra final na ponte entre Santos e Guaruj\u00e1?"},"content":{"rendered":"<p>O ministro dos Portos, Pedro Brito, foi enf\u00e1tico ao afirmar na ter\u00e7a-feira (25) que a palavra final sobre a constru\u00e7\u00e3o da ponte estaiada ligando Santos a Guaruj\u00e1 ser\u00e1 da Codesp. Por sua vez, o Governo de S\u00e3o Paulo est\u00e1 neste momento escolhendo a empresa respons\u00e1vel pelo projeto executivo da pol\u00eamica obra. Assim, fica uma d\u00favida no ar. Quem d\u00e1 a palavra final: Secretaria Especial de Portos ou Governo do Estado? Pelo jeito, os dois querem cumprir este papel.&nbsp;<\/p>\n<p>\nPedro Brito destacou que a ponte estaiada or\u00e7ada em R$ 500 milh\u00f5es oferece uma alternativa \u00e0 travessia de balsas entre Santos e Guaruj\u00e1. Por\u00e9m, ela n\u00e3o pode se tornar um gargalo log\u00edstico e atrapalhar a expans\u00e3o do porto santista. O ministro dos Portos citou a proposta de eleva\u00e7\u00e3o da altura da ponte de 70 para 80 metros e a garantia de que ela ter\u00e1, no Canal do Estu\u00e1rio, um v\u00e3o de 300 metros, permitindo a passagem de dois navios ao mesmo tempo, algo que hoje n\u00e3o existe. <br \/>\n\u201c<br \/>\nA palavra final sobre a constru\u00e7\u00e3o desta ponte ficar\u00e1 com a Codesp, pois o Porto de Santos est\u00e1 em processo de expans\u00e3o e n\u00e3o podemos criar gargalos\u201d, destacou Brito, invocando uma mudan\u00e7a de posi\u00e7\u00e3o da estatal. Sabe-se que, do jeito que est\u00e1, o projeto apresentado pelo governo paulista n\u00e3o agrada as autoridades. Ele prev\u00ea a constru\u00e7\u00e3o de uma ponte que cruzar\u00e1 o porto, mas a ideia \u00e9 proibir a circula\u00e7\u00e3o de caminh\u00f5es, sendo a ponte exclusiva para carros de passeio e motos.&nbsp;<\/p>\n<p>Enquanto o ministro dos Portos diz, com todas as letras, que a palavra final sobre o assunto ser\u00e1 da&nbsp;<br \/>\nCodesp, o secret\u00e1rio de Transportes de S\u00e3o Paulo, Mauro Arce, vai na contram\u00e3o e toca o processo da ponte adiante. Explicou que a contrata\u00e7\u00e3o da empresa que far\u00e1 o projeto executivo da obra est\u00e1 em fase final e, provavelmente a partir do m\u00eas que vem ou em outubro, no mais tardar, prefeituras, Autoridade Portu\u00e1ria e Governo Federal ser\u00e3o chamados para dar sugest\u00f5es.&nbsp;<\/p>\n<p>\u201cTivemos no final de julho um acidente envolvendo um navio desgovernado e uma das balsas que operam na travessia. Ali, ficou claro que alguma coisa precisa ser mudada. O porto vai crescer e n\u00e3o d\u00e1 para conciliar as duas coisas. \u00c9 por isso que propusemos a ponte. E o projeto que apresentei antes pode ser mudado. H\u00e1 tempo para isso. S\u00f3 n\u00e3o podemos nos dar ao luxo de discutirmos o tema indefinidamente. O Governo do Estado quer resolver logo este assunto\u201d. <\/p>\n<p><b>Autor: Porto Gente<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ministro dos Portos, Pedro Brito, foi enf\u00e1tico ao afirmar na ter\u00e7a-feira (25) que a palavra final sobre a constru\u00e7\u00e3o da ponte estaiada ligando Santos a Guaruj\u00e1 ser\u00e1 da Codesp. Por sua vez, o Governo de S\u00e3o Paulo est\u00e1 neste momento escolhendo a empresa respons\u00e1vel pelo projeto executivo da pol\u00eamica obra. Assim, fica uma d\u00favida [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,41],"tags":[],"class_list":{"0":"post-16521","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-noticias","7":"category-transportes"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SEP ou SP: quem dar\u00e1 a palavra final na ponte entre Santos e Guaruj\u00e1? - Instituto de Engenharia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/27\/sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SEP ou SP: quem dar\u00e1 a palavra final na ponte entre Santos e Guaruj\u00e1? - Instituto de Engenharia\" \/>\n<meta property=\"og:description\" content=\"O ministro dos Portos, Pedro Brito, foi enf\u00e1tico ao afirmar na ter\u00e7a-feira (25) que a palavra final sobre a constru\u00e7\u00e3o da ponte estaiada ligando Santos a Guaruj\u00e1 ser\u00e1 da Codesp. Por sua vez, o Governo de S\u00e3o Paulo est\u00e1 neste momento escolhendo a empresa respons\u00e1vel pelo projeto executivo da pol\u00eamica obra. Assim, fica uma d\u00favida [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/27\/sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto de Engenharia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/institutodeengenharia\" \/>\n<meta property=\"article:published_time\" content=\"2009-08-27T22:20:32+00:00\" \/>\n<meta name=\"author\" content=\"TMax Tecnologia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@iengenharia\" \/>\n<meta name=\"twitter:site\" content=\"@iengenharia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"TMax Tecnologia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/27\\\/sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/27\\\/sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja\\\/\"},\"author\":{\"name\":\"TMax Tecnologia\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/person\\\/3b1ff109facef084739fc2edcb9a127f\"},\"headline\":\"SEP ou SP: quem dar\u00e1 a palavra final na ponte entre Santos e Guaruj\u00e1?\",\"datePublished\":\"2009-08-27T22:20:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/27\\\/sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja\\\/\"},\"wordCount\":458,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\"},\"articleSection\":[\"Not\u00edcias\",\"Transportes\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/27\\\/sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/27\\\/sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja\\\/\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/27\\\/sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja\\\/\",\"name\":\"SEP ou SP: quem dar\u00e1 a palavra final na ponte entre Santos e Guaruj\u00e1? - Instituto de Engenharia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#website\"},\"datePublished\":\"2009-08-27T22:20:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/27\\\/sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/27\\\/sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/27\\\/sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SEP ou SP: quem dar\u00e1 a palavra final na ponte entre Santos e Guaruj\u00e1?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\",\"name\":\"Instituto de Engenharia\",\"description\":\"O Instituto de Engenharia promove a Engenharia em benef\u00edcio do desenvolvimento e da qualidade de vida da sociedade.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\",\"name\":\"Instituto de Engenharia\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo-novo-IE2018-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo-novo-IE2018-1.jpg\",\"width\":1486,\"height\":1879,\"caption\":\"Instituto de Engenharia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/institutodeengenharia\",\"https:\\\/\\\/x.com\\\/iengenharia\",\"https:\\\/\\\/www.instagram.com\\\/institutodeengenharia\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/instituto-de-engenharia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCXiCAlsSMe977vamW915HxA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/person\\\/3b1ff109facef084739fc2edcb9a127f\",\"name\":\"TMax Tecnologia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g\",\"caption\":\"TMax Tecnologia\"},\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/author\\\/tmax\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SEP ou SP: quem dar\u00e1 a palavra final na ponte entre Santos e Guaruj\u00e1? - Instituto de Engenharia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/27\/sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja\/","og_locale":"pt_BR","og_type":"article","og_title":"SEP ou SP: quem dar\u00e1 a palavra final na ponte entre Santos e Guaruj\u00e1? - Instituto de Engenharia","og_description":"O ministro dos Portos, Pedro Brito, foi enf\u00e1tico ao afirmar na ter\u00e7a-feira (25) que a palavra final sobre a constru\u00e7\u00e3o da ponte estaiada ligando Santos a Guaruj\u00e1 ser\u00e1 da Codesp. Por sua vez, o Governo de S\u00e3o Paulo est\u00e1 neste momento escolhendo a empresa respons\u00e1vel pelo projeto executivo da pol\u00eamica obra. Assim, fica uma d\u00favida [&hellip;]","og_url":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/27\/sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja\/","og_site_name":"Instituto de Engenharia","article_publisher":"https:\/\/www.facebook.com\/institutodeengenharia","article_published_time":"2009-08-27T22:20:32+00:00","author":"TMax Tecnologia","twitter_card":"summary_large_image","twitter_creator":"@iengenharia","twitter_site":"@iengenharia","twitter_misc":{"Escrito por":"TMax Tecnologia","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/27\/sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja\/#article","isPartOf":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/27\/sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja\/"},"author":{"name":"TMax Tecnologia","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/person\/3b1ff109facef084739fc2edcb9a127f"},"headline":"SEP ou SP: quem dar\u00e1 a palavra final na ponte entre Santos e Guaruj\u00e1?","datePublished":"2009-08-27T22:20:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/27\/sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja\/"},"wordCount":458,"commentCount":0,"publisher":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization"},"articleSection":["Not\u00edcias","Transportes"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/27\/sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/27\/sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja\/","url":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/27\/sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja\/","name":"SEP ou SP: quem dar\u00e1 a palavra final na ponte entre Santos e Guaruj\u00e1? - Instituto de Engenharia","isPartOf":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#website"},"datePublished":"2009-08-27T22:20:32+00:00","breadcrumb":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/27\/sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/27\/sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/27\/sep-ou-sp-quem-dara-a-palavra-final-na-ponte-entre-santos-e-guaruja\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.institutodeengenharia.org.br\/site\/"},{"@type":"ListItem","position":2,"name":"SEP ou SP: quem dar\u00e1 a palavra final na ponte entre Santos e Guaruj\u00e1?"}]},{"@type":"WebSite","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#website","url":"https:\/\/www.institutodeengenharia.org.br\/site\/","name":"Instituto de Engenharia","description":"O Instituto de Engenharia promove a Engenharia em benef\u00edcio do desenvolvimento e da qualidade de vida da sociedade.","publisher":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.institutodeengenharia.org.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization","name":"Instituto de Engenharia","url":"https:\/\/www.institutodeengenharia.org.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2019\/03\/logo-novo-IE2018-1.jpg","contentUrl":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2019\/03\/logo-novo-IE2018-1.jpg","width":1486,"height":1879,"caption":"Instituto de Engenharia"},"image":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/institutodeengenharia","https:\/\/x.com\/iengenharia","https:\/\/www.instagram.com\/institutodeengenharia\/","https:\/\/www.linkedin.com\/company\/instituto-de-engenharia\/","https:\/\/www.youtube.com\/channel\/UCXiCAlsSMe977vamW915HxA"]},{"@type":"Person","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/person\/3b1ff109facef084739fc2edcb9a127f","name":"TMax Tecnologia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g","caption":"TMax Tecnologia"},"url":"https:\/\/www.institutodeengenharia.org.br\/site\/author\/tmax\/"}]}},"_links":{"self":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts\/16521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/comments?post=16521"}],"version-history":[{"count":0,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts\/16521\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/media?parent=16521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/categories?post=16521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/tags?post=16521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}