{"id":16443,"date":"2009-08-18T22:19:10","date_gmt":"2009-08-18T22:19:10","guid":{"rendered":"https:\/\/www.institutodeengenharia.org.br\/?p=16443"},"modified":"2009-08-18T16:42:57","modified_gmt":"2009-08-18T16:42:57","slug":"95-das-exportacoes-passam-pelos-portos","status":"publish","type":"post","link":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/18\/95-das-exportacoes-passam-pelos-portos\/","title":{"rendered":"95% das exporta\u00e7\u00f5es passam pelos portos"},"content":{"rendered":"<p>Um total de 95% das exporta\u00e7\u00f5es passa pelos portos, entretanto, pol\u00edticas de incentivos fiscais ou de redu\u00e7\u00e3o de taxas, quando n\u00e3o existe infraestrutura, s\u00e3o mais alvo de corrup\u00e7\u00e3o do que de atra\u00e7\u00e3o de novos neg\u00f3cios. A afirma\u00e7\u00e3o \u00e9 do ministro Pedro Brito, da Secretaria Especial de Portos da Presid\u00eancia da Rep\u00fablica, que apresentou a palestra &#8220;Os portos brasileiros na perspectiva do S\u00e9culo XXI&#8221;, ontem, no Teatro Celina Queiroz, da Universidade de Fortaleza (Unifor). Para Pedro Brito, a infra-estrutura atrav\u00e9s de portos, estradas, ferrovias, gera\u00e7\u00e3o de energia, suporte de telecomunica\u00e7\u00f5es, \u00e9 a melhor forma de impulsionar o desenvolvimentos dos pa\u00edses. <\/p>\n<p>&#8220;\u00c9 preciso uma pol\u00edtica de Estado forte para enfrentar as dificuldades de infraestrutura&#8221;, disse. Conforme o ministro, os portos, por exemplo, representam uma uni\u00e3o de novos investimentos, atra\u00e7\u00e3o de novos neg\u00f3cios e empregos. Mas, no entanto, necessitam de um sistema log\u00edstico eficiente que permita o funcionamento da cadeia produtiva. Isso passa, primeiramente, segundo Brito, pela exist\u00eancia de rodovias e ferrovias, para o escoamento dos materiais, o que nem sempre existe. <\/p>\n<p>O Porto do Mucuripe, de acordo com o ministro, tem graves problemas de acesso terrestre, na medida em que os caminh\u00f5es n\u00e3o t\u00eam vias preferenciais e que a via ferrovi\u00e1ria passa ao lado das resid\u00eancias a uma velocidade de 10 quil\u00f4metros por hora. &#8220;O Porto do Mucuripe s\u00f3 ser\u00e1 eficiente se houver uma cadeia log\u00edstica que permita isso. Esperamos que a constru\u00e7\u00e3o da Ponte da Sabiaguaba amenize isso&#8221;, disse. <\/p>\n<p>J\u00e1 o Porto do Pec\u00e9m, por outro lado, para Brito, \u00e9 mais moderno e re\u00fane v\u00e1rias caracter\u00edsticas, como a inexist\u00eancia de problemas urbanos, e a sua exist\u00eancia vem conseguindo atrair novos investimentos. A China, conforme Pedro Brito, tem seis dos 10 maiores portos do mundo, enquanto que o Porto de Santos, o maior do Brasil, e por onde passa 25% de tudo que \u00e9 exportado e importado no Brasil, coloca-se como o 38\u00ba do mundo. &#8220;A transforma\u00e7\u00e3o do sudeste asi\u00e1tico \u00e9 baseada na cria\u00e7\u00e3o de infra-estrutura. O governo chin\u00eas decidiu investir US$ 600 bilh\u00f5es em infraestrutura e isso \u00e9 um diferencial&#8221;, explica. <\/p>\n<p>A cria\u00e7\u00e3o de um terminal de passageiros no Porto do Mucuripe, anunciado recentemente pela Secretaria Especial de Portos da Presid\u00eancia da Rep\u00fablica, \u00e9 um dos projetos estruturantes para a Copa de 2014 na sub-sede de Fortaleza. Conforme o titular da Secretaria Especial de Portos da Presid\u00eancia da Rep\u00fablica, ministro Pedro Brito, o terminal est\u00e1 em fase de defini\u00e7\u00f5es, estudos e projeto b\u00e1sico. &#8220;No \u00faltimo fim de semana estivemos com o arquiteto que vai criar o projeto b\u00e1sico do terminal.&nbsp;<\/p>\n<p>Depois disso, n\u00f3s vamos definir a viabilidade econ\u00f4mico-financeira do neg\u00f3cio e estabelecer os volumes de investimentos, estimados inicialmente em R$ 150 milh\u00f5es, e depois vamos licit\u00e1-lo&#8221;, disse. O terminal deve estar pronto antes da Copa de 2014, para atender n\u00e3o s\u00f3 a demanda do evento, mas tamb\u00e9m o mercado de turismo portu\u00e1rio no Cear\u00e1 que \u00e9 crescente. &#8220;Ser\u00e1 uma estrutura moderna com toda a seguran\u00e7a necess\u00e1ria, tipo as que existem nos grandes aeroportos do mundo, para que se tenham at\u00e9 mesmo uma alternativa \u00e0 rede hoteleira, uma vez que os transatl\u00e2nticos poder\u00e3o ficar no pr\u00f3prio terminal e as pessoas v\u00e3o se deslocar apenas durante os jogos&#8221;. <\/p>\n<p><b>Autor: Di\u00e1rio do Nordeste<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um total de 95% das exporta\u00e7\u00f5es passa pelos portos, entretanto, pol\u00edticas de incentivos fiscais ou de redu\u00e7\u00e3o de taxas, quando n\u00e3o existe infraestrutura, s\u00e3o mais alvo de corrup\u00e7\u00e3o do que de atra\u00e7\u00e3o de novos neg\u00f3cios. A afirma\u00e7\u00e3o \u00e9 do ministro Pedro Brito, da Secretaria Especial de Portos da Presid\u00eancia da Rep\u00fablica, que apresentou a palestra [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,41],"tags":[],"class_list":{"0":"post-16443","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-noticias","7":"category-transportes"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>95% das exporta\u00e7\u00f5es passam pelos portos - Instituto de Engenharia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/18\/95-das-exportacoes-passam-pelos-portos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"95% das exporta\u00e7\u00f5es passam pelos portos - Instituto de Engenharia\" \/>\n<meta property=\"og:description\" content=\"Um total de 95% das exporta\u00e7\u00f5es passa pelos portos, entretanto, pol\u00edticas de incentivos fiscais ou de redu\u00e7\u00e3o de taxas, quando n\u00e3o existe infraestrutura, s\u00e3o mais alvo de corrup\u00e7\u00e3o do que de atra\u00e7\u00e3o de novos neg\u00f3cios. A afirma\u00e7\u00e3o \u00e9 do ministro Pedro Brito, da Secretaria Especial de Portos da Presid\u00eancia da Rep\u00fablica, que apresentou a palestra [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/18\/95-das-exportacoes-passam-pelos-portos\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto de Engenharia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/institutodeengenharia\" \/>\n<meta property=\"article:published_time\" content=\"2009-08-18T22:19:10+00:00\" \/>\n<meta name=\"author\" content=\"TMax Tecnologia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@iengenharia\" \/>\n<meta name=\"twitter:site\" content=\"@iengenharia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"TMax Tecnologia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/18\\\/95-das-exportacoes-passam-pelos-portos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/18\\\/95-das-exportacoes-passam-pelos-portos\\\/\"},\"author\":{\"name\":\"TMax Tecnologia\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/person\\\/3b1ff109facef084739fc2edcb9a127f\"},\"headline\":\"95% das exporta\u00e7\u00f5es passam pelos portos\",\"datePublished\":\"2009-08-18T22:19:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/18\\\/95-das-exportacoes-passam-pelos-portos\\\/\"},\"wordCount\":581,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\"},\"articleSection\":[\"Not\u00edcias\",\"Transportes\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/18\\\/95-das-exportacoes-passam-pelos-portos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/18\\\/95-das-exportacoes-passam-pelos-portos\\\/\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/18\\\/95-das-exportacoes-passam-pelos-portos\\\/\",\"name\":\"95% das exporta\u00e7\u00f5es passam pelos portos - Instituto de Engenharia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#website\"},\"datePublished\":\"2009-08-18T22:19:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/18\\\/95-das-exportacoes-passam-pelos-portos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/18\\\/95-das-exportacoes-passam-pelos-portos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/18\\\/95-das-exportacoes-passam-pelos-portos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"95% das exporta\u00e7\u00f5es passam pelos portos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\",\"name\":\"Instituto de Engenharia\",\"description\":\"O Instituto de Engenharia promove a Engenharia em benef\u00edcio do desenvolvimento e da qualidade de vida da sociedade.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\",\"name\":\"Instituto de Engenharia\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo-novo-IE2018-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo-novo-IE2018-1.jpg\",\"width\":1486,\"height\":1879,\"caption\":\"Instituto de Engenharia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/institutodeengenharia\",\"https:\\\/\\\/x.com\\\/iengenharia\",\"https:\\\/\\\/www.instagram.com\\\/institutodeengenharia\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/instituto-de-engenharia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCXiCAlsSMe977vamW915HxA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/person\\\/3b1ff109facef084739fc2edcb9a127f\",\"name\":\"TMax Tecnologia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g\",\"caption\":\"TMax Tecnologia\"},\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/author\\\/tmax\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"95% das exporta\u00e7\u00f5es passam pelos portos - Instituto de Engenharia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/18\/95-das-exportacoes-passam-pelos-portos\/","og_locale":"pt_BR","og_type":"article","og_title":"95% das exporta\u00e7\u00f5es passam pelos portos - Instituto de Engenharia","og_description":"Um total de 95% das exporta\u00e7\u00f5es passa pelos portos, entretanto, pol\u00edticas de incentivos fiscais ou de redu\u00e7\u00e3o de taxas, quando n\u00e3o existe infraestrutura, s\u00e3o mais alvo de corrup\u00e7\u00e3o do que de atra\u00e7\u00e3o de novos neg\u00f3cios. A afirma\u00e7\u00e3o \u00e9 do ministro Pedro Brito, da Secretaria Especial de Portos da Presid\u00eancia da Rep\u00fablica, que apresentou a palestra [&hellip;]","og_url":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/18\/95-das-exportacoes-passam-pelos-portos\/","og_site_name":"Instituto de Engenharia","article_publisher":"https:\/\/www.facebook.com\/institutodeengenharia","article_published_time":"2009-08-18T22:19:10+00:00","author":"TMax Tecnologia","twitter_card":"summary_large_image","twitter_creator":"@iengenharia","twitter_site":"@iengenharia","twitter_misc":{"Escrito por":"TMax Tecnologia","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/18\/95-das-exportacoes-passam-pelos-portos\/#article","isPartOf":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/18\/95-das-exportacoes-passam-pelos-portos\/"},"author":{"name":"TMax Tecnologia","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/person\/3b1ff109facef084739fc2edcb9a127f"},"headline":"95% das exporta\u00e7\u00f5es passam pelos portos","datePublished":"2009-08-18T22:19:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/18\/95-das-exportacoes-passam-pelos-portos\/"},"wordCount":581,"commentCount":0,"publisher":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization"},"articleSection":["Not\u00edcias","Transportes"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/18\/95-das-exportacoes-passam-pelos-portos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/18\/95-das-exportacoes-passam-pelos-portos\/","url":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/18\/95-das-exportacoes-passam-pelos-portos\/","name":"95% das exporta\u00e7\u00f5es passam pelos portos - Instituto de Engenharia","isPartOf":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#website"},"datePublished":"2009-08-18T22:19:10+00:00","breadcrumb":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/18\/95-das-exportacoes-passam-pelos-portos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/18\/95-das-exportacoes-passam-pelos-portos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/18\/95-das-exportacoes-passam-pelos-portos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.institutodeengenharia.org.br\/site\/"},{"@type":"ListItem","position":2,"name":"95% das exporta\u00e7\u00f5es passam pelos portos"}]},{"@type":"WebSite","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#website","url":"https:\/\/www.institutodeengenharia.org.br\/site\/","name":"Instituto de Engenharia","description":"O Instituto de Engenharia promove a Engenharia em benef\u00edcio do desenvolvimento e da qualidade de vida da sociedade.","publisher":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.institutodeengenharia.org.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization","name":"Instituto de Engenharia","url":"https:\/\/www.institutodeengenharia.org.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2019\/03\/logo-novo-IE2018-1.jpg","contentUrl":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2019\/03\/logo-novo-IE2018-1.jpg","width":1486,"height":1879,"caption":"Instituto de Engenharia"},"image":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/institutodeengenharia","https:\/\/x.com\/iengenharia","https:\/\/www.instagram.com\/institutodeengenharia\/","https:\/\/www.linkedin.com\/company\/instituto-de-engenharia\/","https:\/\/www.youtube.com\/channel\/UCXiCAlsSMe977vamW915HxA"]},{"@type":"Person","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/person\/3b1ff109facef084739fc2edcb9a127f","name":"TMax Tecnologia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g","caption":"TMax Tecnologia"},"url":"https:\/\/www.institutodeengenharia.org.br\/site\/author\/tmax\/"}]}},"_links":{"self":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts\/16443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/comments?post=16443"}],"version-history":[{"count":0,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts\/16443\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/media?parent=16443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/categories?post=16443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/tags?post=16443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}