{"id":16343,"date":"2009-08-05T22:17:36","date_gmt":"2009-08-05T22:17:36","guid":{"rendered":"https:\/\/www.institutodeengenharia.org.br\/?p=16343"},"modified":"2009-08-05T17:16:11","modified_gmt":"2009-08-05T17:16:11","slug":"arce-debatera-expansao-do-porto","status":"publish","type":"post","link":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/05\/arce-debatera-expansao-do-porto\/","title":{"rendered":"Arce debater\u00e1 expans\u00e3o do porto"},"content":{"rendered":"<p>O secret\u00e1rio estadual de Transportes, Mauro Arce, confirmou sua presen\u00e7a na 7a edi\u00e7\u00e3o do Santos Export \u00ad F\u00f3rum Nacional para Expans\u00e3o do Porto de Santos, que ser\u00e1 realizado nos pr\u00f3ximos dias 25 e 26, no Mendes Convention Center, em Santos.&nbsp;<\/p>\n<p>A autoridade participar\u00e1 da mesa-redonda O futuro do sistema portu\u00e1rio e do Porto de Santos, marcada para o segundo dia do evento e que abordar\u00e1 os estudos de expans\u00e3o do complexo mar\u00edtimo e a necessidade de novos acessos \u00e0 regi\u00e3o.&nbsp;<\/p>\n<p>Na ocasi\u00e3o, Arce debater\u00e1 o projeto do Estado para construir uma liga\u00e7\u00e3o seca entre Santos e Guaruj\u00e1, assunto que tem gerado diverg\u00eancia entre os representantes do setor.&nbsp;<\/p>\n<p>O Santos Export \u00e9 uma iniciativa do Sistema A Tribuna de Comunica\u00e7\u00e3o, com realiza\u00e7\u00e3o da Una Marketing de Eventos. Os interessados em participar j\u00e1 podem se inscrever atrav\u00e9s do site <a target=\"_blank\" href=\"http:\/\/www.forumsantosexport.com.br\">www.forumsantosexport.com.br<\/a>. O valor da taxa \u00e9 de R$ 450,00, com desconto de 50% para estudantes e professores.&nbsp;<\/p>\n<p>A apresenta\u00e7\u00e3o de Arce dever\u00e1 ser uma das mais esperadas no evento, uma vez que o secret\u00e1rio n\u00e3o participou do \u00faltimo debate sobre a liga\u00e7\u00e3o seca, realizado na \u00faltima segundafeira, na Associa\u00e7\u00e3o de Engenheiros e Arquitetos de Santos, na Cidade. Al\u00e9m disso, o semin\u00e1rio ocorrer\u00e1 dias ap\u00f3s a abertura dos envelopes &#8211;que acontecer\u00e1 no pr\u00f3ximo dia 21&#8211; com as propostas das empresas participantes da licita\u00e7\u00e3o para a realiza\u00e7\u00e3o do projeto-b\u00e1sico de uma ponte entre Santos e Guaruj\u00e1. O estudo ir\u00e1 definir as caracter\u00edsticas do empreendimento.&nbsp;<\/p>\n<p>Em um projeto preliminar, o Estado prop\u00f4s uma ponte com 2,8 quil\u00f4metros de extens\u00e3o, incluindo as rampas de acesso, com eleva\u00e7\u00f5es em 5%. A pista teria quatro faixas, ciclovias e cal\u00e7adas, com uma largura de 20 metros e 70 metros de v\u00e3o livre. Por\u00e9m, empres\u00e1rios j\u00e1 demonstraram que as caracter\u00edsticas podem limitar a expans\u00e3o do Porto de Santos.&nbsp;<\/p>\n<p><strong>Discuss\u00f5es<\/strong>&nbsp;<\/p>\n<p>Com o objetivo de incentivar a discuss\u00e3o e buscar solu\u00e7\u00f5es para a amplia\u00e7\u00e3o e a moderniza\u00e7\u00e3o do Porto, o semin\u00e1rio dever\u00e1 reunir 400 pessoas, entre autoridades e empres\u00e1rios portu\u00e1rios, de transportes, log\u00edstica e com\u00e9rcio exterior.&nbsp;<\/p>\n<p>Tamb\u00e9m participar\u00e1 o ministro-chefe da Secretaria Especial de Portos, Pedro Brito. <br \/>\nOs principais assuntos que ser\u00e3o abordados este ano s\u00e3o a infraestrutura de acessos regionais, a revis\u00e3o do marco regulat\u00f3rio portu\u00e1rio e aduaneiro e a amplia\u00e7\u00e3o da atividade portu\u00e1ria com sustentabilidade ambiental.&nbsp;<\/p>\n<p>O Santos Export tem o patroc\u00ednio das empresas Anhumas, Ciesa, Fertimport, Fosfertil, Libra Terminais, Localfrio, Marimex, Santos-Brasil S.A., Tecondi, TPG (Terminal Portu\u00e1rio do Guaruj\u00e1), Deicmar e Icipar. E conta com o apoio da Associa\u00e7\u00e3o das Empresas do Distrito Industrial e Portu\u00e1rio da Alemoa, da Associa\u00e7\u00e3o Comercial de Santos, do Porto de Santos,da Praticagem de Santos, das Prefeituras de Cubat\u00e3o, Guaruj\u00e1 e Santos e da Universidade Cat\u00f3lica de Santos (UniSantos). <\/p>\n<p><b>Autor: A Tribuna<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O secret\u00e1rio estadual de Transportes, Mauro Arce, confirmou sua presen\u00e7a na 7a edi\u00e7\u00e3o do Santos Export \u00ad F\u00f3rum Nacional para Expans\u00e3o do Porto de Santos, que ser\u00e1 realizado nos pr\u00f3ximos dias 25 e 26, no Mendes Convention Center, em Santos.&nbsp; A autoridade participar\u00e1 da mesa-redonda O futuro do sistema portu\u00e1rio e do Porto de Santos, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,41],"tags":[],"class_list":{"0":"post-16343","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-noticias","7":"category-transportes"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arce debater\u00e1 expans\u00e3o do porto - Instituto de Engenharia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/05\/arce-debatera-expansao-do-porto\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arce debater\u00e1 expans\u00e3o do porto - Instituto de Engenharia\" \/>\n<meta property=\"og:description\" content=\"O secret\u00e1rio estadual de Transportes, Mauro Arce, confirmou sua presen\u00e7a na 7a edi\u00e7\u00e3o do Santos Export \u00ad F\u00f3rum Nacional para Expans\u00e3o do Porto de Santos, que ser\u00e1 realizado nos pr\u00f3ximos dias 25 e 26, no Mendes Convention Center, em Santos.&nbsp; A autoridade participar\u00e1 da mesa-redonda O futuro do sistema portu\u00e1rio e do Porto de Santos, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/05\/arce-debatera-expansao-do-porto\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto de Engenharia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/institutodeengenharia\" \/>\n<meta property=\"article:published_time\" content=\"2009-08-05T22:17:36+00:00\" \/>\n<meta name=\"author\" content=\"TMax Tecnologia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@iengenharia\" \/>\n<meta name=\"twitter:site\" content=\"@iengenharia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"TMax Tecnologia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/05\\\/arce-debatera-expansao-do-porto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/05\\\/arce-debatera-expansao-do-porto\\\/\"},\"author\":{\"name\":\"TMax Tecnologia\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/person\\\/3b1ff109facef084739fc2edcb9a127f\"},\"headline\":\"Arce debater\u00e1 expans\u00e3o do porto\",\"datePublished\":\"2009-08-05T22:17:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/05\\\/arce-debatera-expansao-do-porto\\\/\"},\"wordCount\":518,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\"},\"articleSection\":[\"Not\u00edcias\",\"Transportes\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/05\\\/arce-debatera-expansao-do-porto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/05\\\/arce-debatera-expansao-do-porto\\\/\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/05\\\/arce-debatera-expansao-do-porto\\\/\",\"name\":\"Arce debater\u00e1 expans\u00e3o do porto - Instituto de Engenharia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#website\"},\"datePublished\":\"2009-08-05T22:17:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/05\\\/arce-debatera-expansao-do-porto\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/05\\\/arce-debatera-expansao-do-porto\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/08\\\/05\\\/arce-debatera-expansao-do-porto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arce debater\u00e1 expans\u00e3o do porto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\",\"name\":\"Instituto de Engenharia\",\"description\":\"O Instituto de Engenharia promove a Engenharia em benef\u00edcio do desenvolvimento e da qualidade de vida da sociedade.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\",\"name\":\"Instituto de Engenharia\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo-novo-IE2018-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo-novo-IE2018-1.jpg\",\"width\":1486,\"height\":1879,\"caption\":\"Instituto de Engenharia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/institutodeengenharia\",\"https:\\\/\\\/x.com\\\/iengenharia\",\"https:\\\/\\\/www.instagram.com\\\/institutodeengenharia\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/instituto-de-engenharia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCXiCAlsSMe977vamW915HxA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/person\\\/3b1ff109facef084739fc2edcb9a127f\",\"name\":\"TMax Tecnologia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g\",\"caption\":\"TMax Tecnologia\"},\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/author\\\/tmax\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arce debater\u00e1 expans\u00e3o do porto - Instituto de Engenharia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/05\/arce-debatera-expansao-do-porto\/","og_locale":"pt_BR","og_type":"article","og_title":"Arce debater\u00e1 expans\u00e3o do porto - Instituto de Engenharia","og_description":"O secret\u00e1rio estadual de Transportes, Mauro Arce, confirmou sua presen\u00e7a na 7a edi\u00e7\u00e3o do Santos Export \u00ad F\u00f3rum Nacional para Expans\u00e3o do Porto de Santos, que ser\u00e1 realizado nos pr\u00f3ximos dias 25 e 26, no Mendes Convention Center, em Santos.&nbsp; A autoridade participar\u00e1 da mesa-redonda O futuro do sistema portu\u00e1rio e do Porto de Santos, [&hellip;]","og_url":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/05\/arce-debatera-expansao-do-porto\/","og_site_name":"Instituto de Engenharia","article_publisher":"https:\/\/www.facebook.com\/institutodeengenharia","article_published_time":"2009-08-05T22:17:36+00:00","author":"TMax Tecnologia","twitter_card":"summary_large_image","twitter_creator":"@iengenharia","twitter_site":"@iengenharia","twitter_misc":{"Escrito por":"TMax Tecnologia","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/05\/arce-debatera-expansao-do-porto\/#article","isPartOf":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/05\/arce-debatera-expansao-do-porto\/"},"author":{"name":"TMax Tecnologia","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/person\/3b1ff109facef084739fc2edcb9a127f"},"headline":"Arce debater\u00e1 expans\u00e3o do porto","datePublished":"2009-08-05T22:17:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/05\/arce-debatera-expansao-do-porto\/"},"wordCount":518,"commentCount":0,"publisher":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization"},"articleSection":["Not\u00edcias","Transportes"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/05\/arce-debatera-expansao-do-porto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/05\/arce-debatera-expansao-do-porto\/","url":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/05\/arce-debatera-expansao-do-porto\/","name":"Arce debater\u00e1 expans\u00e3o do porto - Instituto de Engenharia","isPartOf":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#website"},"datePublished":"2009-08-05T22:17:36+00:00","breadcrumb":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/05\/arce-debatera-expansao-do-porto\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/05\/arce-debatera-expansao-do-porto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/08\/05\/arce-debatera-expansao-do-porto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.institutodeengenharia.org.br\/site\/"},{"@type":"ListItem","position":2,"name":"Arce debater\u00e1 expans\u00e3o do porto"}]},{"@type":"WebSite","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#website","url":"https:\/\/www.institutodeengenharia.org.br\/site\/","name":"Instituto de Engenharia","description":"O Instituto de Engenharia promove a Engenharia em benef\u00edcio do desenvolvimento e da qualidade de vida da sociedade.","publisher":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.institutodeengenharia.org.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization","name":"Instituto de Engenharia","url":"https:\/\/www.institutodeengenharia.org.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2019\/03\/logo-novo-IE2018-1.jpg","contentUrl":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2019\/03\/logo-novo-IE2018-1.jpg","width":1486,"height":1879,"caption":"Instituto de Engenharia"},"image":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/institutodeengenharia","https:\/\/x.com\/iengenharia","https:\/\/www.instagram.com\/institutodeengenharia\/","https:\/\/www.linkedin.com\/company\/instituto-de-engenharia\/","https:\/\/www.youtube.com\/channel\/UCXiCAlsSMe977vamW915HxA"]},{"@type":"Person","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/person\/3b1ff109facef084739fc2edcb9a127f","name":"TMax Tecnologia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g","caption":"TMax Tecnologia"},"url":"https:\/\/www.institutodeengenharia.org.br\/site\/author\/tmax\/"}]}},"_links":{"self":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts\/16343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/comments?post=16343"}],"version-history":[{"count":0,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts\/16343\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/media?parent=16343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/categories?post=16343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/tags?post=16343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}