{"id":15791,"date":"2009-04-24T22:08:19","date_gmt":"2009-04-24T22:08:19","guid":{"rendered":"https:\/\/www.institutodeengenharia.org.br\/?p=15791"},"modified":"2009-04-24T15:35:05","modified_gmt":"2009-04-24T15:35:05","slug":"evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia","status":"publish","type":"post","link":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/24\/evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia\/","title":{"rendered":"Evento marca posse de Aluizio de Barros Fagundes para a Presid\u00eancia do Instituto de Engenharia"},"content":{"rendered":"<p>Ontem (23), foi realizado o evento para a posse o engenheiro civil Aluizio de Barros Fagundes como presidente do Instituto de Engenharia para o bi\u00eanio 2009-2011. A cerim\u00f4nia, que aconteceu na sede do Instituto, contou com a presen\u00e7a do prefeito de S\u00e3o Paulo, Gilberto Kassab.&nbsp;<\/p>\n<p>A mesa diretora foi composta por Carlos Eduardo Mendes Gon\u00e7alves, presidente do Conselho Consultivo do Instituto, Otavio de Mattos Silvaris, reitor do Centro Universit\u00e1rio do Instituto Mau\u00e1 de Tecnologia, Luiz Ricardo Pereira Leite, diretor-presidente da Cohab, Edemar de Souza Amorim, ex-presidente do Instituto de Engenharia, M\u00e1rcio Rillo, reitor do Centro Universit\u00e1rio do FEI \u2013 Funda\u00e7\u00e3o Educacional Inaciana \u2013, Maria do Carmo Calijuri, diretora da Escola de Engenharia de S\u00e3o Carlos da USP e Jos\u00e9 Roberto Bernasconi, presidente nacional do Sindicato Nacional das empresas de Arquitetura e Engenharia Consultiva, al\u00e9m do presidente que tomou posse, Aluizio de Barros Fagundes.&nbsp;<\/p>\n<p>Em seu r\u00e1pido discurso, o prefeito Gilberto Kassab lembrou e agradeceu a honraria que teve no \u00faltimo ano quando foi escolhido para receber da casa o t\u00edtulo de Eminente Engenheiro, e pelo fato de o Instituto de Engenharia ter sido durante a \u00faltima gest\u00e3o um dos mais relevantes parceiros da administra\u00e7\u00e3o do munic\u00edpio de S\u00e3o Paulo. \u201cAqui se tem os mais importantes debatedores do desenvolvimento da cidade. Profissionais que nos ajudam a encontrar o rumo para a cidade. Quero poder continuar contando com voc\u00eas, dessa nova gest\u00e3o, pois tenho orgulho de ser engenheiro e s\u00f3cio do Instituto de Engenharia\u201d, disse.&nbsp;<\/p>\n<p>Ao proferir seu discurso, o presidente Aluizio de Barros Fagundes falou da import\u00e2ncia de seu pai na influ\u00eancia, e consequente, contagio pela profiss\u00e3o de engenheiro. \u201cDesde cedo eu o acompanhava nas suas dilig\u00eancias em obras pesadas e de grande significado. De meu pai recebi o cont\u00e1gio da engenharia. N\u00e3o havia como dela escapar. Quero dedicar a ele o privil\u00e9gio de hoje assumir a presid\u00eancia deste querido Instituto de Engenharia\u201d, ressaltou.&nbsp;<\/p>\n<p>Citou que \u201cn\u00e3o podemos nos entregar ao recesso da crise (&#8230;). Para a sociedade paulista e brasileira, tenho a dizer que o Instituto de Engenharia \u00e9 o instrumento de nossa a\u00e7\u00e3o. Nesta casa nasceram, dentre outras entidades, o Crea e o Sindicato da Engenharia. Nesta casa nasceram, dentre outros grandes projetos, o Pr\u00f3 \u00c1lcool e a Cosipa. Fa\u00e7amos do nosso Instituto a fonte de novos rumos para o Pa\u00eds\u201d.&nbsp;<\/p>\n<p>Lembrou que daqui a sete anos o Instituto comemorar\u00e1 seu centen\u00e1rio e que at\u00e9 l\u00e1 deve ser remo\u00e7ada, arejada e reavivada. Para seus dois anos de gest\u00e3o, ele prop\u00f4s preparar um plano de metas consistente e consent\u00e2neo com novos tempos, restabelecendo o \u00edmpeto progressista do Instituto.&nbsp;<\/p>\n<p>Ao passar o cargo, em seu discurso, o ex-presidente Edemar de Souza Amorim ofereceu o seu apoio ao presidente e \u00e0 nova diretoria, e alertou para os percal\u00e7os que ser\u00e3o encontrados ao longo da gest\u00e3o, por\u00e9m ressaltando que \u201c\u00e9 poss\u00edvel levar a miss\u00e3o do Instituto de Engenharia adiante. Transformando-o numa entidade forte, articuladora, l\u00edder e principalmente moderna\u201d. <\/p>\n<p><b>Autor: Isabel Dianin<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ontem (23), foi realizado o evento para a posse o engenheiro civil Aluizio de Barros Fagundes como presidente do Instituto de Engenharia para o bi\u00eanio 2009-2011. A cerim\u00f4nia, que aconteceu na sede do Instituto, contou com a presen\u00e7a do prefeito de S\u00e3o Paulo, Gilberto Kassab.&nbsp; A mesa diretora foi composta por Carlos Eduardo Mendes Gon\u00e7alves, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,6],"tags":[],"class_list":{"0":"post-15791","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-instituto-de-engenharia","7":"category-noticias"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Evento marca posse de Aluizio de Barros Fagundes para a Presid\u00eancia do Instituto de Engenharia - Instituto de Engenharia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/24\/evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Evento marca posse de Aluizio de Barros Fagundes para a Presid\u00eancia do Instituto de Engenharia - Instituto de Engenharia\" \/>\n<meta property=\"og:description\" content=\"Ontem (23), foi realizado o evento para a posse o engenheiro civil Aluizio de Barros Fagundes como presidente do Instituto de Engenharia para o bi\u00eanio 2009-2011. A cerim\u00f4nia, que aconteceu na sede do Instituto, contou com a presen\u00e7a do prefeito de S\u00e3o Paulo, Gilberto Kassab.&nbsp; A mesa diretora foi composta por Carlos Eduardo Mendes Gon\u00e7alves, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/24\/evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto de Engenharia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/institutodeengenharia\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-24T22:08:19+00:00\" \/>\n<meta name=\"author\" content=\"TMax Tecnologia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@iengenharia\" \/>\n<meta name=\"twitter:site\" content=\"@iengenharia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"TMax Tecnologia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/04\\\/24\\\/evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/04\\\/24\\\/evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia\\\/\"},\"author\":{\"name\":\"TMax Tecnologia\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/person\\\/3b1ff109facef084739fc2edcb9a127f\"},\"headline\":\"Evento marca posse de Aluizio de Barros Fagundes para a Presid\u00eancia do Instituto de Engenharia\",\"datePublished\":\"2009-04-24T22:08:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/04\\\/24\\\/evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia\\\/\"},\"wordCount\":547,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\"},\"articleSection\":[\"Instituto de Engenharia\",\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/04\\\/24\\\/evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/04\\\/24\\\/evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia\\\/\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/04\\\/24\\\/evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia\\\/\",\"name\":\"Evento marca posse de Aluizio de Barros Fagundes para a Presid\u00eancia do Instituto de Engenharia - Instituto de Engenharia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#website\"},\"datePublished\":\"2009-04-24T22:08:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/04\\\/24\\\/evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/04\\\/24\\\/evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/04\\\/24\\\/evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Evento marca posse de Aluizio de Barros Fagundes para a Presid\u00eancia do Instituto de Engenharia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\",\"name\":\"Instituto de Engenharia\",\"description\":\"O Instituto de Engenharia promove a Engenharia em benef\u00edcio do desenvolvimento e da qualidade de vida da sociedade.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\",\"name\":\"Instituto de Engenharia\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo-novo-IE2018-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo-novo-IE2018-1.jpg\",\"width\":1486,\"height\":1879,\"caption\":\"Instituto de Engenharia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/institutodeengenharia\",\"https:\\\/\\\/x.com\\\/iengenharia\",\"https:\\\/\\\/www.instagram.com\\\/institutodeengenharia\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/instituto-de-engenharia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCXiCAlsSMe977vamW915HxA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/person\\\/3b1ff109facef084739fc2edcb9a127f\",\"name\":\"TMax Tecnologia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g\",\"caption\":\"TMax Tecnologia\"},\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/author\\\/tmax\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Evento marca posse de Aluizio de Barros Fagundes para a Presid\u00eancia do Instituto de Engenharia - Instituto de Engenharia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/24\/evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia\/","og_locale":"pt_BR","og_type":"article","og_title":"Evento marca posse de Aluizio de Barros Fagundes para a Presid\u00eancia do Instituto de Engenharia - Instituto de Engenharia","og_description":"Ontem (23), foi realizado o evento para a posse o engenheiro civil Aluizio de Barros Fagundes como presidente do Instituto de Engenharia para o bi\u00eanio 2009-2011. A cerim\u00f4nia, que aconteceu na sede do Instituto, contou com a presen\u00e7a do prefeito de S\u00e3o Paulo, Gilberto Kassab.&nbsp; A mesa diretora foi composta por Carlos Eduardo Mendes Gon\u00e7alves, [&hellip;]","og_url":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/24\/evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia\/","og_site_name":"Instituto de Engenharia","article_publisher":"https:\/\/www.facebook.com\/institutodeengenharia","article_published_time":"2009-04-24T22:08:19+00:00","author":"TMax Tecnologia","twitter_card":"summary_large_image","twitter_creator":"@iengenharia","twitter_site":"@iengenharia","twitter_misc":{"Escrito por":"TMax Tecnologia","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/24\/evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia\/#article","isPartOf":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/24\/evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia\/"},"author":{"name":"TMax Tecnologia","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/person\/3b1ff109facef084739fc2edcb9a127f"},"headline":"Evento marca posse de Aluizio de Barros Fagundes para a Presid\u00eancia do Instituto de Engenharia","datePublished":"2009-04-24T22:08:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/24\/evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia\/"},"wordCount":547,"commentCount":0,"publisher":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization"},"articleSection":["Instituto de Engenharia","Not\u00edcias"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/24\/evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/24\/evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia\/","url":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/24\/evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia\/","name":"Evento marca posse de Aluizio de Barros Fagundes para a Presid\u00eancia do Instituto de Engenharia - Instituto de Engenharia","isPartOf":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#website"},"datePublished":"2009-04-24T22:08:19+00:00","breadcrumb":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/24\/evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/24\/evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/24\/evento-marca-posse-de-aluizio-de-barros-fagundes-para-a-presidencia-do-instituto-de-engenharia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.institutodeengenharia.org.br\/site\/"},{"@type":"ListItem","position":2,"name":"Evento marca posse de Aluizio de Barros Fagundes para a Presid\u00eancia do Instituto de Engenharia"}]},{"@type":"WebSite","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#website","url":"https:\/\/www.institutodeengenharia.org.br\/site\/","name":"Instituto de Engenharia","description":"O Instituto de Engenharia promove a Engenharia em benef\u00edcio do desenvolvimento e da qualidade de vida da sociedade.","publisher":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.institutodeengenharia.org.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization","name":"Instituto de Engenharia","url":"https:\/\/www.institutodeengenharia.org.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2019\/03\/logo-novo-IE2018-1.jpg","contentUrl":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2019\/03\/logo-novo-IE2018-1.jpg","width":1486,"height":1879,"caption":"Instituto de Engenharia"},"image":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/institutodeengenharia","https:\/\/x.com\/iengenharia","https:\/\/www.instagram.com\/institutodeengenharia\/","https:\/\/www.linkedin.com\/company\/instituto-de-engenharia\/","https:\/\/www.youtube.com\/channel\/UCXiCAlsSMe977vamW915HxA"]},{"@type":"Person","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/person\/3b1ff109facef084739fc2edcb9a127f","name":"TMax Tecnologia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g","caption":"TMax Tecnologia"},"url":"https:\/\/www.institutodeengenharia.org.br\/site\/author\/tmax\/"}]}},"_links":{"self":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts\/15791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/comments?post=15791"}],"version-history":[{"count":0,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts\/15791\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/media?parent=15791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/categories?post=15791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/tags?post=15791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}