{"id":15783,"date":"2009-04-23T22:08:10","date_gmt":"2009-04-23T22:08:10","guid":{"rendered":"https:\/\/www.institutodeengenharia.org.br\/?p=15783"},"modified":"2009-04-23T16:45:01","modified_gmt":"2009-04-23T16:45:01","slug":"reacao-biologica","status":"publish","type":"post","link":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/23\/reacao-biologica\/","title":{"rendered":"Rea\u00e7\u00e3o biol\u00f3gica"},"content":{"rendered":"<p>A partir de um estudo realizado na Escola de Engenharia de S\u00e3o Carlos, da Universidade de S\u00e3o Paulo (USP), um pesquisador desenvolveu e testou um reator para tratamento biol\u00f3gico de efluentes industriais contendo sulfato.&nbsp;<\/p>\n<p>O reator, desenvolvido pelo engenheiro Arnaldo Sarti durante sua pesquisa de p\u00f3s-doutorado, com apoio da FAPESP, foi instalado no Laborat\u00f3rio de Processos Biol\u00f3gicos (LPE), da EESC. A inven\u00e7\u00e3o, capaz de reduzir em at\u00e9 92% a concentra\u00e7\u00e3o de sulfato, j\u00e1 foi patenteada.&nbsp;<\/p>\n<p>De acordo com Sarti, o \u00edon sulfato, assim como outros compostos de enxofre, causa grande preju\u00edzo ambiental, degradando mananciais e est\u00e1 presente em efluentes da ind\u00fastria de papel e celulose, refinarias de \u00f3leos comest\u00edveis, curtumes e processos que utilizam \u00e1cido sulf\u00farico como mat\u00e9ria-prima.&nbsp;<\/p>\n<p>\u201cOs resultados, em termos de redu\u00e7\u00e3o de sulfato, foram muito expressivos e permitem concluir que a aplica\u00e7\u00e3o de tratamento biol\u00f3gico em efluente industrial contendo sulfato, com uso de reator anaer\u00f3bio, poder\u00e1 ser utilizada em larga escala, no futuro, at\u00e9 mesmo para o tratamento de outras \u00e1guas residu\u00e1rias ricas em sulfato\u201d, disse Sarti \u00e0 Ag\u00eancia FAPESP.&nbsp;<\/p>\n<p>O p\u00f3s-doutorado de Sarti, conclu\u00eddo h\u00e1 um ano, foi orientado por Eugenio Foresti, professor da EESC que coordena um projeto tem\u00e1tico apoiado pela FAPESP: \u201cDesenvolvimento de sistemas combinados de tratamento de \u00e1guas residu\u00e1rias visando \u00e0 remo\u00e7\u00e3o de poluentes e \u00e0 recupera\u00e7\u00e3o de energia e de produtos dos ciclos de carbono, nitrog\u00eanio e enxofre\u201d.&nbsp;<\/p>\n<p>O processo, segundo Sarti, consiste na remo\u00e7\u00e3o do \u00edon sulfato por meio da a\u00e7\u00e3o de microrganismos anaer\u00f3bios dispostos dentro de um reator preenchido com carv\u00e3o \u2013 um suporte inerte que garante a manuten\u00e7\u00e3o dos organismos no sistema por ader\u00eancia f\u00edsica.&nbsp;<\/p>\n<p>\u201cA remo\u00e7\u00e3o biol\u00f3gica de sulfato \u00e9 a alternativa com melhor rela\u00e7\u00e3o custo-benef\u00edcio comparativamente aos processos f\u00edsicos. Dependendo da concentra\u00e7\u00e3o de sulfato na \u00e1gua residu\u00e1ria, pode ser interessante a uni\u00e3o de processos f\u00edsicos e qu\u00edmicos aos processos biotecnol\u00f3gicos\u201d, disse o engenheiro.&nbsp;<\/p>\n<p>Sarti explicou que o reator anaer\u00f3bio \u00e9 operado em batelada, isto \u00e9, o tratamento biol\u00f3gico \u00e9 realizado em uma sequ\u00eancia operacional que compreende diversas etapas. No caso, o tratamento \u00e9 feito em quatro etapas: alimenta\u00e7\u00e3o, agita\u00e7\u00e3o, rea\u00e7\u00e3o e descarte. O ciclo total de opera\u00e7\u00e3o \u00e9 de 48 horas.&nbsp;<\/p>\n<p>\u201cPrimeiro o l\u00edquido \u00e9 introduzido, durante uma hora. As duas etapas seguintes levam 46 horas: o l\u00edquido \u00e9 agitado com uma bomba juntamente com a massa de microrganismos e, em seguida, a etapa de rea\u00e7\u00e3o \u00e9 feita por meio de decanta\u00e7\u00e3o do l\u00edquido e sedimenta\u00e7\u00e3o da biomassa. Finalmente, levamos mais uma hora para que o l\u00edquido tratado seja descartado\u201d, explicou.&nbsp;<\/p>\n<p>Antes de ser alimentado com a \u00e1gua contendo sulfato, o reator \u00e9 alimentado com uma massa de microrganismos proveniente de esgoto sanit\u00e1rio. Colonizando o material suporte, os microrganismos aderem \u00e0 superf\u00edcie e formam um biofilme. O processo \u00e9 completado com o uso de etanol, que permite a forma\u00e7\u00e3o de \u00e1cido ac\u00e9tico ap\u00f3s a redu\u00e7\u00e3o do sulfato.&nbsp;<\/p>\n<p>O maior problema enfrentado na opera\u00e7\u00e3o desse tipo de reator, segundo Sarti, \u00e9 a manuten\u00e7\u00e3o de uma quantidade de biomassa suficientemente alta. Esse problema operacional foi resolvido com a utiliza\u00e7\u00e3o dos suportes inertes no interior da unidade.&nbsp;<\/p>\n<p>\u201cA superf\u00edcie dos materiais inertes \u00e9 o local utilizado preferencialmente pelos microrganismos no desenvolvimento de suas atividades metab\u00f3licas. A popula\u00e7\u00e3o de microrganismos aderidos apresenta maior atividade metab\u00f3lica do que os que ficam em suspens\u00e3o\u201d, disse o pesquisador.&nbsp;<\/p>\n<p>O processo de redu\u00e7\u00e3o do sulfato, de acordo com Sarti, \u00e9 realizado por um grupo de microrganismos amplamente distribu\u00eddos na natureza que t\u00eam a capacidade de utilizar sulfato na respira\u00e7\u00e3o anaer\u00f3bia, gerando sulfeto.&nbsp;<\/p>\n<p>\u201cExistem diversos organismos, incluindo plantas superiores, algas, fungos e muitos procariontes, que utilizam sulfato como fonte de enxofre para a s\u00edntese celular, realizando a redu\u00e7\u00e3o assimilativa do \u00edon sulfato. Esse processo gera sulfeto, que \u00e9 imediatamente convertido a enxofre org\u00e2nico na forma de amino\u00e1cidos\u201d, disse.&nbsp;<\/p>\n<p>O reator foi constru\u00eddo em fibra de vidro, com volume total de 1,2 m\u00b3 e com meio suporte composto de carv\u00e3o mineral. Foram necess\u00e1rios cerca de 500 quilos de massa de carv\u00e3o mineral para a composi\u00e7\u00e3o do leito no interior do equipamento. \u201cA op\u00e7\u00e3o pelo carv\u00e3o mineral vem da facilidade de manuseio em termos de n\u00e3o exigir dispositivo especial para a sua fixa\u00e7\u00e3o ou manuten\u00e7\u00e3o no interior da unidade\u201d, contou.&nbsp;<\/p>\n<p>O sulfato utilizado no reator durante os testes era proveniente de \u00e1gua residu\u00e1ria industrial gerada no processo de sulfona\u00e7\u00e3o de \u00f3leos vegetais, no qual se utilizava \u00e1cido sulf\u00farico como mat\u00e9ria-prima. Esses \u00f3leos s\u00e3o utilizados especificamente para acabamento de couros animais.&nbsp;<\/p>\n<p>\u201cToda a id\u00e9ia surgiu a partir do problema real de uma ind\u00fastria da regi\u00e3o que gera uma alt\u00edssima concentra\u00e7\u00e3o de sulfato: cerca de 120 mil miligramas por litro. N\u00e3o desenvolvemos o reator para a empresa, mas fomos atra\u00eddos pela possibilidade de lidar com uma quantidade de efluentes reais em grande escala. O LPE j\u00e1 havia produzido outros reatores, mas sempre para efluentes sint\u00e9ticos em pequena escala\u201d, disse Sarti.&nbsp;<\/p>\n<p>De acordo com Sarti, ser\u00e1 preciso agora trabalhar no desenvolvimento de um m\u00e9todo de p\u00f3s-tratamento para o sulfeto gerado pelo processo. O forte odor produzido tamb\u00e9m \u00e9 uma preocupa\u00e7\u00e3o.&nbsp;<\/p>\n<p>\u201cEsse tratamento complementar dever\u00e1 remover os sulfetos dissolvidos, transformando-os em enxofre elementar. Isso tornar\u00e1 o processo mais sustent\u00e1vel do ponto de vista ambiental e econ\u00f4mico, j\u00e1 que o Brasil importa, anualmente, aproximadamente dois milh\u00f5es de toneladas de compostos de enxofre, gastando cerca de US$ 108 milh\u00f5es. O enxofre tem grande aplica\u00e7\u00e3o na agricultura e nas industrias qu\u00edmicas\u201d, declarou. <\/p>\n<p><b>Autor: Ag\u00eancia FAPESP<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir de um estudo realizado na Escola de Engenharia de S\u00e3o Carlos, da Universidade de S\u00e3o Paulo (USP), um pesquisador desenvolveu e testou um reator para tratamento biol\u00f3gico de efluentes industriais contendo sulfato.&nbsp; O reator, desenvolvido pelo engenheiro Arnaldo Sarti durante sua pesquisa de p\u00f3s-doutorado, com apoio da FAPESP, foi instalado no Laborat\u00f3rio de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,35],"tags":[],"class_list":{"0":"post-15783","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-noticias","7":"category-pesquisa-e-desenvolvimento"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rea\u00e7\u00e3o biol\u00f3gica - Instituto de Engenharia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/23\/reacao-biologica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rea\u00e7\u00e3o biol\u00f3gica - Instituto de Engenharia\" \/>\n<meta property=\"og:description\" content=\"A partir de um estudo realizado na Escola de Engenharia de S\u00e3o Carlos, da Universidade de S\u00e3o Paulo (USP), um pesquisador desenvolveu e testou um reator para tratamento biol\u00f3gico de efluentes industriais contendo sulfato.&nbsp; O reator, desenvolvido pelo engenheiro Arnaldo Sarti durante sua pesquisa de p\u00f3s-doutorado, com apoio da FAPESP, foi instalado no Laborat\u00f3rio de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/23\/reacao-biologica\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto de Engenharia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/institutodeengenharia\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-23T22:08:10+00:00\" \/>\n<meta name=\"author\" content=\"TMax Tecnologia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@iengenharia\" \/>\n<meta name=\"twitter:site\" content=\"@iengenharia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"TMax Tecnologia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/04\\\/23\\\/reacao-biologica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/04\\\/23\\\/reacao-biologica\\\/\"},\"author\":{\"name\":\"TMax Tecnologia\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/person\\\/3b1ff109facef084739fc2edcb9a127f\"},\"headline\":\"Rea\u00e7\u00e3o biol\u00f3gica\",\"datePublished\":\"2009-04-23T22:08:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/04\\\/23\\\/reacao-biologica\\\/\"},\"wordCount\":999,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\"},\"articleSection\":[\"Not\u00edcias\",\"Pesquisa e Desenvolvimento\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/04\\\/23\\\/reacao-biologica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/04\\\/23\\\/reacao-biologica\\\/\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/04\\\/23\\\/reacao-biologica\\\/\",\"name\":\"Rea\u00e7\u00e3o biol\u00f3gica - Instituto de Engenharia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#website\"},\"datePublished\":\"2009-04-23T22:08:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/04\\\/23\\\/reacao-biologica\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/04\\\/23\\\/reacao-biologica\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/04\\\/23\\\/reacao-biologica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rea\u00e7\u00e3o biol\u00f3gica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\",\"name\":\"Instituto de Engenharia\",\"description\":\"O Instituto de Engenharia promove a Engenharia em benef\u00edcio do desenvolvimento e da qualidade de vida da sociedade.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\",\"name\":\"Instituto de Engenharia\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo-novo-IE2018-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo-novo-IE2018-1.jpg\",\"width\":1486,\"height\":1879,\"caption\":\"Instituto de Engenharia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/institutodeengenharia\",\"https:\\\/\\\/x.com\\\/iengenharia\",\"https:\\\/\\\/www.instagram.com\\\/institutodeengenharia\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/instituto-de-engenharia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCXiCAlsSMe977vamW915HxA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/person\\\/3b1ff109facef084739fc2edcb9a127f\",\"name\":\"TMax Tecnologia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g\",\"caption\":\"TMax Tecnologia\"},\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/author\\\/tmax\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rea\u00e7\u00e3o biol\u00f3gica - Instituto de Engenharia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/23\/reacao-biologica\/","og_locale":"pt_BR","og_type":"article","og_title":"Rea\u00e7\u00e3o biol\u00f3gica - Instituto de Engenharia","og_description":"A partir de um estudo realizado na Escola de Engenharia de S\u00e3o Carlos, da Universidade de S\u00e3o Paulo (USP), um pesquisador desenvolveu e testou um reator para tratamento biol\u00f3gico de efluentes industriais contendo sulfato.&nbsp; O reator, desenvolvido pelo engenheiro Arnaldo Sarti durante sua pesquisa de p\u00f3s-doutorado, com apoio da FAPESP, foi instalado no Laborat\u00f3rio de [&hellip;]","og_url":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/23\/reacao-biologica\/","og_site_name":"Instituto de Engenharia","article_publisher":"https:\/\/www.facebook.com\/institutodeengenharia","article_published_time":"2009-04-23T22:08:10+00:00","author":"TMax Tecnologia","twitter_card":"summary_large_image","twitter_creator":"@iengenharia","twitter_site":"@iengenharia","twitter_misc":{"Escrito por":"TMax Tecnologia","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/23\/reacao-biologica\/#article","isPartOf":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/23\/reacao-biologica\/"},"author":{"name":"TMax Tecnologia","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/person\/3b1ff109facef084739fc2edcb9a127f"},"headline":"Rea\u00e7\u00e3o biol\u00f3gica","datePublished":"2009-04-23T22:08:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/23\/reacao-biologica\/"},"wordCount":999,"commentCount":0,"publisher":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization"},"articleSection":["Not\u00edcias","Pesquisa e Desenvolvimento"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/23\/reacao-biologica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/23\/reacao-biologica\/","url":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/23\/reacao-biologica\/","name":"Rea\u00e7\u00e3o biol\u00f3gica - Instituto de Engenharia","isPartOf":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#website"},"datePublished":"2009-04-23T22:08:10+00:00","breadcrumb":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/23\/reacao-biologica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/23\/reacao-biologica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/04\/23\/reacao-biologica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.institutodeengenharia.org.br\/site\/"},{"@type":"ListItem","position":2,"name":"Rea\u00e7\u00e3o biol\u00f3gica"}]},{"@type":"WebSite","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#website","url":"https:\/\/www.institutodeengenharia.org.br\/site\/","name":"Instituto de Engenharia","description":"O Instituto de Engenharia promove a Engenharia em benef\u00edcio do desenvolvimento e da qualidade de vida da sociedade.","publisher":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.institutodeengenharia.org.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization","name":"Instituto de Engenharia","url":"https:\/\/www.institutodeengenharia.org.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2019\/03\/logo-novo-IE2018-1.jpg","contentUrl":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2019\/03\/logo-novo-IE2018-1.jpg","width":1486,"height":1879,"caption":"Instituto de Engenharia"},"image":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/institutodeengenharia","https:\/\/x.com\/iengenharia","https:\/\/www.instagram.com\/institutodeengenharia\/","https:\/\/www.linkedin.com\/company\/instituto-de-engenharia\/","https:\/\/www.youtube.com\/channel\/UCXiCAlsSMe977vamW915HxA"]},{"@type":"Person","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/person\/3b1ff109facef084739fc2edcb9a127f","name":"TMax Tecnologia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g","caption":"TMax Tecnologia"},"url":"https:\/\/www.institutodeengenharia.org.br\/site\/author\/tmax\/"}]}},"_links":{"self":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts\/15783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/comments?post=15783"}],"version-history":[{"count":0,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts\/15783\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/media?parent=15783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/categories?post=15783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/tags?post=15783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}