{"id":15684,"date":"2009-03-31T22:06:28","date_gmt":"2009-03-31T22:06:28","guid":{"rendered":"https:\/\/www.institutodeengenharia.org.br\/?p=15684"},"modified":"2009-03-31T15:41:21","modified_gmt":"2009-03-31T15:41:21","slug":"laboratorio-de-competencias","status":"publish","type":"post","link":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/03\/31\/laboratorio-de-competencias\/","title":{"rendered":"Laborat\u00f3rio de compet\u00eancias"},"content":{"rendered":"<p>Em meio \u00e0 forte crise econ\u00f4mica mundial que tem levado \u00e0 desacelera\u00e7\u00e3o dos neg\u00f3cios e conseq\u00fcentemente do avan\u00e7o tecnol\u00f3gico na ind\u00fastria de m\u00e1quinas e equipamentos, comemoramos neste m\u00eas de mar\u00e7o uma data especial para a engenharia da mobilidade brasileira. H\u00e1 15 anos uma nova atividade estudantil revolucionou o processo de prepara\u00e7\u00e3o dos futuros engenheiros, focando a cria\u00e7\u00e3o de um novo perfil de profissional, mais qualificado, inovador, com vis\u00e3o estrat\u00e9gica e capacidade de se relacionar em equipe.&nbsp;<\/p>\n<p>E, com isso, ser capaz de ajudar o Pa\u00eds a ganhar posi\u00e7\u00e3o de destaque no cen\u00e1rio mundial. A especializa\u00e7\u00e3o dessa m\u00e3o-de-obra vem do Projeto Baja SAE, uma empreitada que come\u00e7ou em 1995 e que chega \u00e0 sua 15\u00ba edi\u00e7\u00e3o com aproximadamente 700 estudantes de engenharia buscando experi\u00eancia pr\u00e1tica para atuar na ind\u00fastria.&nbsp;<\/p>\n<p>Pioneiro no Brasil, o programa atualiza o futuro engenheiro sobre o que a ind\u00fastria est\u00e1 precisando em rela\u00e7\u00e3o \u00e0 compet\u00eancia profissional. Essa atualiza\u00e7\u00e3o est\u00e1 dispon\u00edvel a todos os universit\u00e1rios de engenharia, do Norte ao Sul do Pa\u00eds, atrav\u00e9s do desafio de conceber, projetar, construir e operar um ve\u00edculo off-road. Para alcan\u00e7ar este objetivo, os alunos acabam envolvidos em um ambiente real de desenvolvimento de produto, com todas as suas atividades correlatas, como aplica\u00e7\u00e3o de conceitos t\u00e9cnicos, viabilidade financeira, log\u00edstica, e cumprimento de prazos. O resultado deste trabalho \u00e9 mostrado ao p\u00fablico atrav\u00e9s de uma competi\u00e7\u00e3o de engenharia, onde os projetos ser\u00e3o avaliados individualmente e comparativamente. Tudo sob os olhos de exigentes ju\u00edzes especialistas da \u00e1rea da mobilidade.&nbsp;<\/p>\n<p>Ao aceitarem o desafio, os participantes aprendem engenharia na pr\u00e1tica, mas sem a press\u00e3o do \u2018acertar de primeira\u2019, situa\u00e7\u00e3o requerida por motivos \u00f3bvios quando estiverem atuando na ind\u00fastria. \u00c9 o momento certo de inovar sem medo de errar, aprender novos conceitos e tecnologias. Foi neste ambiente que eu e tantos outros colegas desenvolvemos grande parte de nossa capacita\u00e7\u00e3o t\u00e9cnica e administrativa, que foram os pilares de nossa carreira profissional. Agora, juntamente com um time de mais de 100 volunt\u00e1rios, ajudo na prepara\u00e7\u00e3o das novas gera\u00e7\u00f5es de engenheiros para o competitivo mercado de trabalho que espera ansiosamente a chegada destes novos talentos.&nbsp;<\/p>\n<p>A velocidade com que a tecnologia avan\u00e7a obriga uma constante atualiza\u00e7\u00e3o por parte dos profissionais. Uma das principais vantagens do Projeto Baja SAE pode ser visto neste \u00e2mbito. Vejamos o exemplo das ferramentas computacionais, imprescind\u00edveis hoje no desenvolvimento de ve\u00edculos. As empresas s\u00e3o obrigadas a investir quantidades enormes de dinheiro no treinamento de seus profissionais cada vez que novos softwares s\u00e3o disponibilizados.&nbsp;<\/p>\n<p>O \u201cbajeiro\u201d, designa\u00e7\u00e3o popular daqueles que participam do Projeto Baja SAE, tem a oportunidade de trabalhar com essas ferramentas ainda no per\u00edodo de gradua\u00e7\u00e3o, reduzindo muito a necessidade de treinamento. Junte-se a isso a n\u00edtida facilidade que as novas gera\u00e7\u00f5es t\u00eam de se adaptar ao uso de ferramentas computacionais, j\u00e1 podemos perceber pelo menos um motivo deste rec\u00e9m-formado ser t\u00e3o valioso para a ind\u00fastria.&nbsp;<\/p>\n<p>Podemos ver essa incr\u00edvel evolu\u00e7\u00e3o na capacita\u00e7\u00e3o dos alunos atrav\u00e9s de uma r\u00e1pida compara\u00e7\u00e3o dos Baja SAE de 15 anos atr\u00e1s com os atuais. No in\u00edcio, com pouco ou quase nenhum recurso computacional, os ve\u00edculos eram projetados \u201cno papel\u201d, o que dificultava muito as an\u00e1lises e possibilidade de otimiza\u00e7\u00e3o, resultando em ve\u00edculos com mais de 200 kg e velocidade que n\u00e3o superava os 40 km\/h. Hoje, com os diversos recursos de simula\u00e7\u00e3o e ferramentas tipo CAD\/CAM, os ve\u00edculos mesclam o uso de materiais leves, como alum\u00ednio, fibra de carbono e tit\u00e2nio; usam pneus para terrenos espec\u00edficos, e possuem sistemas de transmiss\u00e3o e suspens\u00e3o testados virtualmente. N\u00e3o \u00e9 raro encontrarmos ve\u00edculos com menos de 130kg atingindo quase 60 km\/h, com integridade estrutural superior aos modelos antigos. Al\u00e9m disso, o t\u00e3o falado sistema de telemetria da Formula 1 j\u00e1 n\u00e3o \u00e9 mais novidade, s\u00e3o muitas as equipes que acompanham em tempo real, nos boxes, as rea\u00e7\u00f5es do ve\u00edculo durante a prova.&nbsp;<\/p>\n<p>\u00c9 fato que o primeiro programa de competi\u00e7\u00e3o para graduandos de engenharia da SAE BRASIL ainda n\u00e3o saiu da fase da adolesc\u00eancia. Mas pelos seus boxes e pistas de barro, desde a antiga pista Guido Caloi em S\u00e3o Paulo, passando pelo Aut\u00f3dromo de Interlagos e depois na tranq\u00fcila Piracicaba, j\u00e1 passaram mais de 10 mil bajeiros.&nbsp;<\/p>\n<p>Espalhados pelo mundo, eles mostram talento principalmente em empresas do ramo automotivo, mas tamb\u00e9m em consultorias, setores de m\u00e1quinas e ferramentas e at\u00e9 na \u00e1rea aeron\u00e1utica. Alguns j\u00e1 conquistam cargos de chefia. Outros partiram para a \u00e1rea de competi\u00e7\u00f5es, incluindo Stock Car, provas de rally, incluindo o Rally Dacar e at\u00e9 mesmo \u00e0 Formula 1, mostrando que o sonho de muitos pode sim tornar-se realidade. Ano a ano observamos cada vez mais portas se abrindo para esse laborat\u00f3rio de compet\u00eancias.&nbsp;<\/p>\n<p><em>*Rafael Fassina Marques \u00e9 engenheiro da Embraer e diretor geral da 15\u00aa Competi\u00e7\u00e3o Baja SAE BRASIL-PETROBRAS <br \/>\n<\/em><\/p>\n<p><b>Autor: Assessoria de imprensa<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em meio \u00e0 forte crise econ\u00f4mica mundial que tem levado \u00e0 desacelera\u00e7\u00e3o dos neg\u00f3cios e conseq\u00fcentemente do avan\u00e7o tecnol\u00f3gico na ind\u00fastria de m\u00e1quinas e equipamentos, comemoramos neste m\u00eas de mar\u00e7o uma data especial para a engenharia da mobilidade brasileira. H\u00e1 15 anos uma nova atividade estudantil revolucionou o processo de prepara\u00e7\u00e3o dos futuros engenheiros, focando [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,35],"tags":[],"class_list":{"0":"post-15684","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-noticias","7":"category-pesquisa-e-desenvolvimento"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Laborat\u00f3rio de compet\u00eancias - Instituto de Engenharia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/03\/31\/laboratorio-de-competencias\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Laborat\u00f3rio de compet\u00eancias - Instituto de Engenharia\" \/>\n<meta property=\"og:description\" content=\"Em meio \u00e0 forte crise econ\u00f4mica mundial que tem levado \u00e0 desacelera\u00e7\u00e3o dos neg\u00f3cios e conseq\u00fcentemente do avan\u00e7o tecnol\u00f3gico na ind\u00fastria de m\u00e1quinas e equipamentos, comemoramos neste m\u00eas de mar\u00e7o uma data especial para a engenharia da mobilidade brasileira. H\u00e1 15 anos uma nova atividade estudantil revolucionou o processo de prepara\u00e7\u00e3o dos futuros engenheiros, focando [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/03\/31\/laboratorio-de-competencias\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto de Engenharia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/institutodeengenharia\" \/>\n<meta property=\"article:published_time\" content=\"2009-03-31T22:06:28+00:00\" \/>\n<meta name=\"author\" content=\"TMax Tecnologia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@iengenharia\" \/>\n<meta name=\"twitter:site\" content=\"@iengenharia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"TMax Tecnologia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/03\\\/31\\\/laboratorio-de-competencias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/03\\\/31\\\/laboratorio-de-competencias\\\/\"},\"author\":{\"name\":\"TMax Tecnologia\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/person\\\/3b1ff109facef084739fc2edcb9a127f\"},\"headline\":\"Laborat\u00f3rio de compet\u00eancias\",\"datePublished\":\"2009-03-31T22:06:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/03\\\/31\\\/laboratorio-de-competencias\\\/\"},\"wordCount\":887,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\"},\"articleSection\":[\"Not\u00edcias\",\"Pesquisa e Desenvolvimento\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/03\\\/31\\\/laboratorio-de-competencias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/03\\\/31\\\/laboratorio-de-competencias\\\/\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/03\\\/31\\\/laboratorio-de-competencias\\\/\",\"name\":\"Laborat\u00f3rio de compet\u00eancias - Instituto de Engenharia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#website\"},\"datePublished\":\"2009-03-31T22:06:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/03\\\/31\\\/laboratorio-de-competencias\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/03\\\/31\\\/laboratorio-de-competencias\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/2009\\\/03\\\/31\\\/laboratorio-de-competencias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Laborat\u00f3rio de compet\u00eancias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\",\"name\":\"Instituto de Engenharia\",\"description\":\"O Instituto de Engenharia promove a Engenharia em benef\u00edcio do desenvolvimento e da qualidade de vida da sociedade.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#organization\",\"name\":\"Instituto de Engenharia\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo-novo-IE2018-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/logo-novo-IE2018-1.jpg\",\"width\":1486,\"height\":1879,\"caption\":\"Instituto de Engenharia\"},\"image\":{\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/institutodeengenharia\",\"https:\\\/\\\/x.com\\\/iengenharia\",\"https:\\\/\\\/www.instagram.com\\\/institutodeengenharia\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/instituto-de-engenharia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCXiCAlsSMe977vamW915HxA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/#\\\/schema\\\/person\\\/3b1ff109facef084739fc2edcb9a127f\",\"name\":\"TMax Tecnologia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g\",\"caption\":\"TMax Tecnologia\"},\"url\":\"https:\\\/\\\/www.institutodeengenharia.org.br\\\/site\\\/author\\\/tmax\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Laborat\u00f3rio de compet\u00eancias - Instituto de Engenharia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/03\/31\/laboratorio-de-competencias\/","og_locale":"pt_BR","og_type":"article","og_title":"Laborat\u00f3rio de compet\u00eancias - Instituto de Engenharia","og_description":"Em meio \u00e0 forte crise econ\u00f4mica mundial que tem levado \u00e0 desacelera\u00e7\u00e3o dos neg\u00f3cios e conseq\u00fcentemente do avan\u00e7o tecnol\u00f3gico na ind\u00fastria de m\u00e1quinas e equipamentos, comemoramos neste m\u00eas de mar\u00e7o uma data especial para a engenharia da mobilidade brasileira. H\u00e1 15 anos uma nova atividade estudantil revolucionou o processo de prepara\u00e7\u00e3o dos futuros engenheiros, focando [&hellip;]","og_url":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/03\/31\/laboratorio-de-competencias\/","og_site_name":"Instituto de Engenharia","article_publisher":"https:\/\/www.facebook.com\/institutodeengenharia","article_published_time":"2009-03-31T22:06:28+00:00","author":"TMax Tecnologia","twitter_card":"summary_large_image","twitter_creator":"@iengenharia","twitter_site":"@iengenharia","twitter_misc":{"Escrito por":"TMax Tecnologia","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/03\/31\/laboratorio-de-competencias\/#article","isPartOf":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/03\/31\/laboratorio-de-competencias\/"},"author":{"name":"TMax Tecnologia","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/person\/3b1ff109facef084739fc2edcb9a127f"},"headline":"Laborat\u00f3rio de compet\u00eancias","datePublished":"2009-03-31T22:06:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/03\/31\/laboratorio-de-competencias\/"},"wordCount":887,"commentCount":0,"publisher":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization"},"articleSection":["Not\u00edcias","Pesquisa e Desenvolvimento"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.institutodeengenharia.org.br\/site\/2009\/03\/31\/laboratorio-de-competencias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/03\/31\/laboratorio-de-competencias\/","url":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/03\/31\/laboratorio-de-competencias\/","name":"Laborat\u00f3rio de compet\u00eancias - Instituto de Engenharia","isPartOf":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#website"},"datePublished":"2009-03-31T22:06:28+00:00","breadcrumb":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/03\/31\/laboratorio-de-competencias\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.institutodeengenharia.org.br\/site\/2009\/03\/31\/laboratorio-de-competencias\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/2009\/03\/31\/laboratorio-de-competencias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.institutodeengenharia.org.br\/site\/"},{"@type":"ListItem","position":2,"name":"Laborat\u00f3rio de compet\u00eancias"}]},{"@type":"WebSite","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#website","url":"https:\/\/www.institutodeengenharia.org.br\/site\/","name":"Instituto de Engenharia","description":"O Instituto de Engenharia promove a Engenharia em benef\u00edcio do desenvolvimento e da qualidade de vida da sociedade.","publisher":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.institutodeengenharia.org.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#organization","name":"Instituto de Engenharia","url":"https:\/\/www.institutodeengenharia.org.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2019\/03\/logo-novo-IE2018-1.jpg","contentUrl":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-content\/uploads\/2019\/03\/logo-novo-IE2018-1.jpg","width":1486,"height":1879,"caption":"Instituto de Engenharia"},"image":{"@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/institutodeengenharia","https:\/\/x.com\/iengenharia","https:\/\/www.instagram.com\/institutodeengenharia\/","https:\/\/www.linkedin.com\/company\/instituto-de-engenharia\/","https:\/\/www.youtube.com\/channel\/UCXiCAlsSMe977vamW915HxA"]},{"@type":"Person","@id":"https:\/\/www.institutodeengenharia.org.br\/site\/#\/schema\/person\/3b1ff109facef084739fc2edcb9a127f","name":"TMax Tecnologia","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f912434ef7f389c92cb311fcdae346af848465d638912574b3c669070f797701?s=96&d=mm&r=g","caption":"TMax Tecnologia"},"url":"https:\/\/www.institutodeengenharia.org.br\/site\/author\/tmax\/"}]}},"_links":{"self":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts\/15684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/comments?post=15684"}],"version-history":[{"count":0,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/posts\/15684\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/media?parent=15684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/categories?post=15684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.institutodeengenharia.org.br\/site\/wp-json\/wp\/v2\/tags?post=15684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}